{"id":3,"date":"2022-04-29T18:03:08","date_gmt":"2022-04-29T18:03:08","guid":{"rendered":"https:\/\/cirefluvial.com\/?page_id=3"},"modified":"2022-12-29T11:12:20","modified_gmt":"2022-12-29T10:12:20","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/cirefluvial.com\/pt\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de Privacidad"},"content":{"rendered":"<h4 class=\"wp-block-heading\">I. POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS<\/h4>\n\n\n\n<p>Respetando lo establecido en la legislaci\u00f3n vigente,&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;(en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Leyes que incorpora esta pol\u00edtica de privacidad<\/h4>\n\n\n\n<p>Esta pol\u00edtica de privacidad est\u00e1 adaptada a la normativa espa\u00f1ola y europea vigente en materia de protecci\u00f3n de datos personales en internet. En concreto, la misma respeta las siguientes normas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD).<\/li>\n\n\n\n<li>La Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales (LOPD-GDD).<\/li>\n\n\n\n<li>El Real Decreto 1720\/2007, de 21 de diciembre, por el que se aprueba el Reglamento de desarrollo de la Ley Org\u00e1nica 15\/1999, de 13 de diciembre, de Protecci\u00f3n de Datos de Car\u00e1cter Personal (RDLOPD).<\/li>\n\n\n\n<li>La Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI-CE).<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Identidad del responsable del tratamiento de los datos personales<\/h4>\n\n\n\n<p>El responsable del tratamiento de los datos personales recogidos en\u00a0Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial\u00a0es:\u00a0Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial, provista de NIF\/CIF:\u00a0G85631729\u00a0e inscrito en:\u00a0Registro Nacional de Asociaciones\u00a0con los siguientes datos registrales:\u00a0Grupo 1, Secci\u00f3n 1, N\u00famero Nacional 592241, cuyo responsable de tratamiento de datos es:\u00a0D\u00f1a. Carolina Herrad\u00f3n Jurado\u00a0(en adelante, Responsable del tratamiento). Sus datos de contacto son los siguientes:<\/p>\n\n\n\n<p>Direcci\u00f3n:&nbsp;Departamento de Geograf\u00eda y Ordenaci\u00f3n del Territorio C\/ Pedro Cerbuna, s\/n \u2022 Universidad de Zaragoza \u2022 50009 Zaragoza<\/p>\n\n\n\n<p>Tel\u00e9fono de contacto:\u00a0622 742 334<\/p>\n\n\n\n<p>Email de contacto:&nbsp;info@cirefluvial.com<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Registro de Datos de Car\u00e1cter Personal<\/h4>\n\n\n\n<p>En cumplimiento de lo establecido en el RGPD y la LOPD-GDD, le informamos que los datos personales recabados por&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial, mediante los formularios extendidos en sus p\u00e1ginas quedar\u00e1n incorporados y ser\u00e1n tratados en nuestro fichero con el fin de poder facilitar, agilizar y cumplir los compromisos establecidos entre&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;y el Usuario o el mantenimiento de la relaci\u00f3n que se establezca en los formularios que este rellene, o para atender una solicitud o consulta del mismo. Asimismo, de conformidad con lo previsto en el RGPD y la LOPD-GDD, salvo que sea de aplicaci\u00f3n la excepci\u00f3n prevista en el art\u00edculo 30.5 del RGPD, se mantiene un registro de actividades de tratamiento que especifica, seg\u00fan sus finalidades, las actividades de tratamiento llevadas a cabo y las dem\u00e1s circunstancias establecidas en el RGPD.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Principios aplicables al tratamiento de los datos personales<\/h4>\n\n\n\n<p>El tratamiento de los datos personales del Usuario se someter\u00e1 a los siguientes principios recogidos en el art\u00edculo 5 del RGPD y en el art\u00edculo 4 y siguientes de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Principio de licitud, lealtad y transparencia: se requerir\u00e1 en todo momento el consentimiento del Usuario previa informaci\u00f3n completamente transparente de los fines para los cuales se recogen los datos personales.<\/li>\n\n\n\n<li>Principio de limitaci\u00f3n de la finalidad: los datos personales ser\u00e1n recogidos con fines determinados, expl\u00edcitos y leg\u00edtimos.<\/li>\n\n\n\n<li>Principio de minimizaci\u00f3n de datos: los datos personales recogidos ser\u00e1n \u00fanicamente los estrictamente necesarios en relaci\u00f3n con los fines para los que son tratados.<\/li>\n\n\n\n<li>Principio de exactitud: los datos personales deben ser exactos y estar siempre actualizados.<\/li>\n\n\n\n<li>Principio de limitaci\u00f3n del plazo de conservaci\u00f3n: los datos personales solo ser\u00e1n mantenidos de forma que se permita la identificaci\u00f3n del Usuario durante el tiempo necesario para los fines de su tratamiento.<\/li>\n\n\n\n<li>Principio de integridad y confidencialidad: los datos personales ser\u00e1n tratados de manera que se garantice su seguridad y confidencialidad.<\/li>\n\n\n\n<li>Principio de responsabilidad proactiva: el Responsable del tratamiento ser\u00e1 responsable de asegurar que los principios anteriores se cumplen.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Categor\u00edas de datos personales<\/h4>\n\n\n\n<p>Las categor\u00edas de datos que se tratan en&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;son \u00fanicamente datos identificativos. En ning\u00fan caso, se tratan categor\u00edas especiales de datos personales en el sentido del art\u00edculo 9 del RGPD.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Base legal para el tratamiento de los datos personales<\/h4>\n\n\n\n<p>La base legal para el tratamiento de los datos personales es el consentimiento.&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;se compromete a recabar el consentimiento expreso y verificable del Usuario para el tratamiento de sus datos personales para uno o varios fines espec\u00edficos.<\/p>\n\n\n\n<p>El Usuario tendr\u00e1 derecho a retirar su consentimiento en cualquier momento. Ser\u00e1 tan f\u00e1cil retirar el consentimiento como darlo. Como regla general, la retirada del consentimiento no condicionar\u00e1 el uso del Sitio Web.<\/p>\n\n\n\n<p>En las ocasiones en las que el Usuario deba o pueda facilitar sus datos a trav\u00e9s de formularios para realizar consultas, solicitar informaci\u00f3n o por motivos relacionados con el contenido del Sitio Web, se le informar\u00e1 en caso de que la cumplimentaci\u00f3n de alguno de ellos sea obligatoria debido a que los mismos sean imprescindibles para el correcto desarrollo de la operaci\u00f3n realizada.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Fines del tratamiento a que se destinan los datos personales<\/h4>\n\n\n\n<p>Los datos personales son recabados y gestionados por&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;con la finalidad de poder facilitar, agilizar y cumplir los compromisos establecidos entre el Sitio Web y el Usuario o el mantenimiento de la relaci\u00f3n que se establezca en los formularios que este \u00faltimo rellene o para atender una solicitud o consulta.<\/p>\n\n\n\n<p>Igualmente, los datos podr\u00e1n ser utilizados con una finalidad comercial de personalizaci\u00f3n, operativa y estad\u00edstica, y actividades propias del objeto social de&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial, as\u00ed como para la extracci\u00f3n, almacenamiento de datos y estudios de marketing para adecuar el Contenido ofertado al Usuario, as\u00ed como mejorar la calidad, funcionamiento y navegaci\u00f3n por el Sitio Web.<\/p>\n\n\n\n<p>En el momento en que se obtengan los datos personales, se informar\u00e1 al Usuario acerca del fin o fines espec\u00edficos del tratamiento a que se destinar\u00e1n los datos personales; es decir, del uso o usos que se dar\u00e1 a la informaci\u00f3n recopilada.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Per\u00edodos de retenci\u00f3n de los datos personales<\/h4>\n\n\n\n<p>Los datos personales solo ser\u00e1n retenidos durante el tiempo m\u00ednimo necesario para los fines de su tratamiento y, en todo caso, \u00fanicamente durante el siguiente plazo:&nbsp;18 meses, o hasta que el Usuario solicite su supresi\u00f3n.<\/p>\n\n\n\n<p>En el momento en que se obtengan los datos personales, se informar\u00e1 al Usuario acerca del plazo durante el cual se conservar\u00e1n los datos personales o, cuando eso no sea posible, los criterios utilizados para determinar este plazo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Destinatarios de los datos personales<\/h4>\n\n\n\n<p>Los datos personales del Usuario ser\u00e1n compartidos con los siguientes destinatarios o categor\u00edas de destinatarios:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Arsys Internet S.L.U. con domicilio en C\/ Madre de Dios n\u00ba 21, 26004, Logro\u00f1o (La Rioja) Espa\u00f1a<\/pre>\n\n\n\n<p>En caso de que el Responsable del tratamiento tenga la intenci\u00f3n de transferir datos personales a un tercer pa\u00eds u organizaci\u00f3n internacional, en el momento en que se obtengan los datos personales, se informar\u00e1 al Usuario acerca del tercer pa\u00eds u organizaci\u00f3n internacional al cual se tiene la intenci\u00f3n de transferir los datos, as\u00ed como de la existencia o ausencia de una decisi\u00f3n de adecuaci\u00f3n de la Comisi\u00f3n.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Datos personales de menores de edad<\/h4>\n\n\n\n<p>Respetando lo establecido en los art\u00edculos 8 del RGPD y 7 de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales, solo los mayores de 14 a\u00f1os podr\u00e1n otorgar su consentimiento para el tratamiento de sus datos personales de forma l\u00edcita por&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial. Si se trata de un menor de 14 a\u00f1os, ser\u00e1 necesario el consentimiento de los padres o tutores para el tratamiento, y este solo se considerar\u00e1 l\u00edcito en la medida en la que los mismos lo hayan autorizado.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Secreto y seguridad de los datos personales<\/h4>\n\n\n\n<p>Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos, de forma que se garantice la seguridad de los datos de car\u00e1cter personal y se evite la destrucci\u00f3n, p\u00e9rdida o alteraci\u00f3n accidental o il\u00edcita de datos personales transmitidos, conservados o tratados de otra forma, o la comunicaci\u00f3n o acceso no autorizados a dichos datos.<\/p>\n\n\n\n<p>El Sitio Web cuenta con un certificado SSL (Secure Socket Layer), que asegura que los datos personales se transmiten de forma segura y confidencial, al ser la transmisi\u00f3n de los datos entre el servidor y el Usuario, y en retroalimentaci\u00f3n, totalmente cifrada o encriptada.<\/p>\n\n\n\n<p>Sin embargo, debido a que&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;no puede garantizar la inexpugnabilidad de internet ni la ausencia total de hackers u otros que accedan de modo fraudulento a los datos personales, el Responsable del tratamiento se compromete a comunicar al Usuario sin dilaci\u00f3n indebida cuando ocurra una violaci\u00f3n de la seguridad de los datos personales que sea probable que entra\u00f1e un alto riesgo para los derechos y libertades de las personas f\u00edsicas. Siguiendo lo establecido en el art\u00edculo 4 del RGPD, se entiende por violaci\u00f3n de la seguridad de los datos personales toda violaci\u00f3n de la seguridad que ocasione la destrucci\u00f3n, p\u00e9rdida o alteraci\u00f3n accidental o il\u00edcita de datos personales transmitidos, conservados o tratados de otra forma, o la comunicaci\u00f3n o acceso no autorizados a dichos datos.<\/p>\n\n\n\n<p>Los datos personales ser\u00e1n tratados como confidenciales por el Responsable del tratamiento, quien se compromete a informar de y a garantizar por medio de una obligaci\u00f3n legal o contractual que dicha confidencialidad sea respetada por sus empleados, asociados, y toda persona a la cual le haga accesible la informaci\u00f3n.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Derechos derivados del tratamiento de los datos personales<\/h4>\n\n\n\n<p>El Usuario tiene sobre&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;y podr\u00e1, por tanto, ejercer frente al Responsable del tratamiento los siguientes derechos reconocidos en el RGPD y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Derecho de acceso:<\/em>&nbsp;Es el derecho del Usuario a obtener confirmaci\u00f3n de si&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;est\u00e1 tratando o no sus datos personales y, en caso afirmativo, obtener informaci\u00f3n sobre sus datos concretos de car\u00e1cter personal y del tratamiento que&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;haya realizado o realice, as\u00ed como, entre otra, de la informaci\u00f3n disponible sobre el origen de dichos datos y los destinatarios de las comunicaciones realizadas o previstas de los mismos.<\/li>\n\n\n\n<li><em>Derecho de rectificaci\u00f3n:<\/em>&nbsp;Es el derecho del Usuario a que se modifiquen sus datos personales que resulten ser inexactos o, teniendo en cuenta los fines del tratamiento, incompletos.<\/li>\n\n\n\n<li><em>Derecho de supresi\u00f3n (\u00abel derecho al olvido\u00bb):<\/em>&nbsp;Es el derecho del Usuario, siempre que la legislaci\u00f3n vigente no establezca lo contrario, a obtener la supresi\u00f3n de sus datos personales cuando estos ya no sean necesarios para los fines para los cuales fueron recogidos o tratados; el Usuario haya retirado su consentimiento al tratamiento y este no cuente con otra base legal; el Usuario se oponga al tratamiento y no exista otro motivo leg\u00edtimo para continuar con el mismo; los datos personales hayan sido tratados il\u00edcitamente; los datos personales deban suprimirse en cumplimiento de una obligaci\u00f3n legal; o los datos personales hayan sido obtenidos producto de una oferta directa de servicios de la sociedad de la informaci\u00f3n a un menor de 14 a\u00f1os. Adem\u00e1s de suprimir los datos, el Responsable del tratamiento, teniendo en cuenta la tecnolog\u00eda disponible y el coste de su aplicaci\u00f3n, deber\u00e1 adoptar medidas razonables para informar a los responsables que est\u00e9n tratando los datos personales de la solicitud del interesado de supresi\u00f3n de cualquier enlace a esos datos personales.<\/li>\n\n\n\n<li><em>Derecho a la limitaci\u00f3n del tratamiento:<\/em>&nbsp;Es el derecho del Usuario a limitar el tratamiento de sus datos personales. El Usuario tiene derecho a obtener la limitaci\u00f3n del tratamiento cuando impugne la exactitud de sus datos personales; el tratamiento sea il\u00edcito; el Responsable del tratamiento ya no necesite los datos personales, pero el Usuario lo necesite para hacer reclamaciones; y cuando el Usuario se haya opuesto al tratamiento.<\/li>\n\n\n\n<li><em>Derecho a la portabilidad de los datos:<\/em>&nbsp;En caso de que el tratamiento se efect\u00fae por medios automatizados, el Usuario tendr\u00e1 derecho a recibir del Responsable del tratamiento sus datos personales en un formato estructurado, de uso com\u00fan y lectura mec\u00e1nica, y a transmitirlos a otro responsable del tratamiento. Siempre que sea t\u00e9cnicamente posible, el Responsable del tratamiento transmitir\u00e1 directamente los datos a ese otro responsable.<\/li>\n\n\n\n<li><em>Derecho de oposici\u00f3n:<\/em>&nbsp;Es el derecho del Usuario a que no se lleve a cabo el tratamiento de sus datos de car\u00e1cter personal o se cese el tratamiento de los mismos por parte de&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial.<\/li>\n\n\n\n<li><em>Derecho a no ser objeto de una decisi\u00f3n basada \u00fanicamente en el tratamiento automatizado, incluida la elaboraci\u00f3n de perfiles:<\/em>&nbsp;Es el derecho del Usuario a no ser objeto de una decisi\u00f3n individualizada basada \u00fanicamente en el tratamiento automatizado de sus datos personales, incluida la elaboraci\u00f3n de perfiles, existente salvo que la legislaci\u00f3n vigente establezca lo contrario.<\/li>\n<\/ul>\n\n\n\n<p>As\u00ed pues, el Usuario podr\u00e1 ejercitar sus derechos mediante comunicaci\u00f3n escrita dirigida al Responsable del tratamiento con la referencia \u00abRGPD-cirefluvial.com\u00bb, especificando:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nombre, apellidos del Usuario y copia del DNI. En los casos en que se admita la representaci\u00f3n, ser\u00e1 tambi\u00e9n necesaria la identificaci\u00f3n por el mismo medio de la persona que representa al Usuario, as\u00ed como el documento acreditativo de la representaci\u00f3n. La fotocopia del DNI podr\u00e1 ser sustituida, por cualquier otro medio v\u00e1lido en derecho que acredite la identidad.<\/li>\n\n\n\n<li>Petici\u00f3n con los motivos espec\u00edficos de la solicitud o informaci\u00f3n a la que se quiere acceder.<\/li>\n\n\n\n<li>Domicilio a efecto de notificaciones.<\/li>\n\n\n\n<li>Fecha y firma del solicitante.<\/li>\n\n\n\n<li>Todo documento que acredite la petici\u00f3n que formula.<\/li>\n<\/ul>\n\n\n\n<p>Esta solicitud y todo otro documento adjunto podr\u00e1 enviarse a la siguiente direcci\u00f3n y\/o correo electr\u00f3nico:<\/p>\n\n\n\n<p>Direcci\u00f3n postal:&nbsp;Departamento de Geograf\u00eda y Ordenaci\u00f3n del Territorio C\/ Pedro Cerbuna, s\/n \u2022 Universidad de Zaragoza \u2022 50009 Zaragoza<\/p>\n\n\n\n<p>Correo electr\u00f3nico:&nbsp;info@cirefluvial.com<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Enlaces a sitios web de terceros<\/h4>\n\n\n\n<p>El Sitio Web puede incluir hiperv\u00ednculos o enlaces que permiten acceder a p\u00e1ginas web de terceros distintos de&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial, y que por tanto no son operados por&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial. Los titulares de dichos sitios web dispondr\u00e1n de sus propias pol\u00edticas de protecci\u00f3n de datos, siendo ellos mismos, en cada caso, responsables de sus propios ficheros y de sus propias pr\u00e1cticas de privacidad.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Reclamaciones ante la autoridad de control<\/h4>\n\n\n\n<p>En caso de que el Usuario considere que existe un problema o infracci\u00f3n de la normativa vigente en la forma en la que se est\u00e1n tratando sus datos personales, tendr\u00e1 derecho a la tutela judicial efectiva y a presentar una reclamaci\u00f3n ante una autoridad de control, en particular, en el Estado en el que tenga su residencia habitual, lugar de trabajo o lugar de la supuesta infracci\u00f3n. En el caso de Espa\u00f1a, la autoridad de control es la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (https:\/\/www.aepd.es\/).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">II. ACEPTACI\u00d3N Y CAMBIOS EN ESTA POL\u00cdTICA DE PRIVACIDAD<\/h4>\n\n\n\n<p>Es necesario que el Usuario haya le\u00eddo y est\u00e9 conforme con las condiciones sobre la protecci\u00f3n de datos de car\u00e1cter personal contenidas en esta Pol\u00edtica de Privacidad, as\u00ed como que acepte el tratamiento de sus datos personales para que el Responsable del tratamiento pueda proceder al mismo en la forma, durante los plazos y para las finalidades indicadas. El uso del Sitio Web implicar\u00e1 la aceptaci\u00f3n de la Pol\u00edtica de Privacidad del mismo.<\/p>\n\n\n\n<p>Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;se reserva el derecho a modificar su Pol\u00edtica de Privacidad, de acuerdo a su propio criterio, o motivado por un cambio legislativo, jurisprudencial o doctrinal de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos. Los cambios o actualizaciones de esta Pol\u00edtica de Privacidad no ser\u00e1n notificados de forma expl\u00edcita al Usuario. Se recomienda al Usuario consultar esta p\u00e1gina de forma peri\u00f3dica para estar al tanto de los \u00faltimos cambios o actualizaciones.<\/p>\n\n\n\n<p>Esta Pol\u00edtica de Privacidad fue actualizada para adaptarse al Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD) y a la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales.<\/p>\n\n\n\n<p>Este documento de Pol\u00edtica de Privacidad de un sitio web ha sido creado mediante el generador de&nbsp;<a href=\"https:\/\/textos-legales.edgartamarit.com\/\">plantilla de pol\u00edtica de privacidad<\/a>&nbsp;online el d\u00eda 26\/09\/2022.<\/p>","protected":false},"excerpt":{"rendered":"<p>I. POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS Respetando lo establecido en la legislaci\u00f3n vigente,&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;(en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos. Leyes que incorpora esta pol\u00edtica de privacidad Esta pol\u00edtica de &#8230; <a title=\"Pol\u00edtica de Privacidad\" class=\"read-more\" href=\"https:\/\/cirefluvial.com\/pt\/politica-de-privacidad\/\" aria-label=\"Leia mais sobre Pol\u00edtica de Privacidad\">Ler mais<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"editor_plus_copied_stylings":"{}","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Privacidad - CIREF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cirefluvial.com\/pt\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidad - CIREF\" \/>\n<meta property=\"og:description\" content=\"I. POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS Respetando lo establecido en la legislaci\u00f3n vigente,&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;(en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos. Leyes que incorpora esta pol\u00edtica de privacidad Esta pol\u00edtica de ... Ler mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cirefluvial.com\/pt\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"CIREF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-29T10:12:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Cirefluvial\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cirefluvial.com\/politica-de-privacidad\/\",\"url\":\"https:\/\/cirefluvial.com\/politica-de-privacidad\/\",\"name\":\"Pol\u00edtica de Privacidad - CIREF\",\"isPartOf\":{\"@id\":\"https:\/\/cirefluvial.com\/#website\"},\"datePublished\":\"2022-04-29T18:03:08+00:00\",\"dateModified\":\"2022-12-29T10:12:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cirefluvial.com\/politica-de-privacidad\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cirefluvial.com\/politica-de-privacidad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cirefluvial.com\/politica-de-privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/cirefluvial.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cirefluvial.com\/#website\",\"url\":\"https:\/\/cirefluvial.com\/\",\"name\":\"CIREF\",\"description\":\"Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial\",\"publisher\":{\"@id\":\"https:\/\/cirefluvial.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cirefluvial.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cirefluvial.com\/#organization\",\"name\":\"Centro Iberico de Restauraci\u00f3n Fluvial\",\"url\":\"https:\/\/cirefluvial.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png\",\"contentUrl\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png\",\"width\":212,\"height\":80,\"caption\":\"Centro Iberico de Restauraci\u00f3n Fluvial\"},\"image\":{\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/\",\"https:\/\/x.com\/Cirefluvial\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Privacidad - CIREF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cirefluvial.com\/pt\/politica-de-privacidad\/","og_locale":"pt_PT","og_type":"article","og_title":"Pol\u00edtica de Privacidad - CIREF","og_description":"I. POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS Respetando lo establecido en la legislaci\u00f3n vigente,&nbsp;Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial&nbsp;(en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos. Leyes que incorpora esta pol\u00edtica de privacidad Esta pol\u00edtica de ... Ler mais","og_url":"https:\/\/cirefluvial.com\/pt\/politica-de-privacidad\/","og_site_name":"CIREF","article_publisher":"https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/","article_modified_time":"2022-12-29T10:12:20+00:00","twitter_card":"summary_large_image","twitter_site":"@Cirefluvial","twitter_misc":{"Tempo estimado de leitura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cirefluvial.com\/politica-de-privacidad\/","url":"https:\/\/cirefluvial.com\/politica-de-privacidad\/","name":"Pol\u00edtica de Privacidad - CIREF","isPartOf":{"@id":"https:\/\/cirefluvial.com\/#website"},"datePublished":"2022-04-29T18:03:08+00:00","dateModified":"2022-12-29T10:12:20+00:00","breadcrumb":{"@id":"https:\/\/cirefluvial.com\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cirefluvial.com\/politica-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cirefluvial.com\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cirefluvial.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidad"}]},{"@type":"WebSite","@id":"https:\/\/cirefluvial.com\/#website","url":"https:\/\/cirefluvial.com\/","name":"CIREF","description":"Centro Ib\u00e9rico de Restauro Fluvial","publisher":{"@id":"https:\/\/cirefluvial.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cirefluvial.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/cirefluvial.com\/#organization","name":"Centro Iberico de Restauraci\u00f3n Fluvial","url":"https:\/\/cirefluvial.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/","url":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png","contentUrl":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png","width":212,"height":80,"caption":"Centro Iberico de Restauraci\u00f3n Fluvial"},"image":{"@id":"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/","https:\/\/x.com\/Cirefluvial"]}]}},"_links":{"self":[{"href":"https:\/\/cirefluvial.com\/pt\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cirefluvial.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cirefluvial.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cirefluvial.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cirefluvial.com\/pt\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":3,"href":"https:\/\/cirefluvial.com\/pt\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":5621,"href":"https:\/\/cirefluvial.com\/pt\/wp-json\/wp\/v2\/pages\/3\/revisions\/5621"}],"wp:attachment":[{"href":"https:\/\/cirefluvial.com\/pt\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}