{"id":7885,"date":"2026-01-21T18:38:28","date_gmt":"2026-01-21T17:38:28","guid":{"rendered":"https:\/\/cirefluvial.com\/?p=7885"},"modified":"2026-01-21T18:38:29","modified_gmt":"2026-01-21T17:38:29","slug":"sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones","status":"publish","type":"post","link":"https:\/\/cirefluvial.com\/en\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/","title":{"rendered":"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones."},"content":{"rendered":"<p class=\"eplus-wrapper\"><strong>1. Introducci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Es frecuente, desgraciadamente, que en determinados medios de comunicaci\u00f3n, redes sociales e incluso en algunos foros presuntamente t\u00e9cnicos, se hable sin demasiado rigor de todas estas infraestructuras (en el caso de pantanos, tipo de terreno), y sus possibles demoliciones confundiendo conceptos y obviando frecuentemente lo contemplado por las normativas vigentes en especial en materia de aguas y medio ambiente y empleando t\u00e9rminos no coincidentes con las definiciones ling\u00fc\u00edsticas correspondientes.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Ello es aprovechado por determinados sectores pol\u00edticos y grupos de presi\u00f3n, vinculados en general al negacionismo clim\u00e1tico y ambiental, para hacer llegar a la sociedad mensajes err\u00f3neos, cuando no claramente malintencionados, que deben ser aclarados desde el mundo acad\u00e9mico y las asociaciones de defensa del medio ambiente.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Por ello se considera conveniente recordar las correspondientes definiciones y exponer como se econtempla en las normativas vigentes sus possibles demoliciones y cuales son los objetivos de estas actuaciones.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>2. Azudes<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>Se trata de una construcci\u00f3n con nombre de origen \u00e1rabe que se realizaba habitualmente con el objetivo de elevar el nivel de agua de un arroyo o r\u00edo con el fin de parar y derivar parte del caudal a las acequias o canales cercanos, situados generalmente en los bordes, para facilitar con ello el riego de los campos y cultivos de la zona, el funcionamiento antiguamente de molinos, la producci\u00f3n de energia hidroel\u00e9ctrica o suministros de agua para abastecimientos diversos.<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Si acudimos al diccionario,<a href=\"https:\/\/dle.rae.es\/azud\">seg\u00fan la RAE<\/a>, la palabra azud puede tener dos acepciones. Por un lado, la de una \u00ab<em>m\u00e1quina en forma de rueda que, movida por la corriente de un r\u00edo, saca agua para regar los campos\u00bb<\/em>. Pero adem\u00e1s, es la \u00ab<em>barrera hecha en los r\u00edos con el fin de facilitar el desv\u00edo de parte del caudal para riego y otros usos<\/em>\u00bb. El origen de la palabra azud es, como ya se ha citado, \u00e1rabe, pueblo que fue el que impuls\u00f3 la transformaci\u00f3n en el uso de las aguas en la pen\u00ednsula ib\u00e9rica durante 8 siglos. En \u00e1rabe, la palabra azud (sudd), quiere decir \u00abdique\u00bb.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><em>No obstante es todav\u00eda frecuente referirse a los azudes como <\/em><em><strong>\u00abpeque\u00f1as presas\u00bb.<\/strong><\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Si analizamos el t\u00e9rmino en ingl\u00e9s, para \u00abazud\u00bb aparece <em>\u00abweir\u00bb,<\/em> cuya definici\u00f3n segun <em>Oxford WORDPOWER Dictionary, <\/em>es \u00ab<em>A type of wall that is built across a river to stop or change the direction of the flow of water\u00bb.<\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>3. Presas<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Las presas son estructuras hidr\u00e1ulicas de <em><u><strong>grandes dimensiones<\/strong><\/u><\/em> que permiten almacenar o retener agua para aprovecharla en actividades como el riego, el consumo humano, la generaci\u00f3n de energ\u00eda el\u00e9ctrica, entre otras.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">As\u00ed ya se observa una importante diferencia, si bien no cuantificada per\u00f2 f\u00e1cil de comprender, de las Presas en relaci\u00f3n a los Azudes, que s\u00f3n sus <strong>\u00ab<\/strong><em><u><strong>grandes dimensiones<\/strong><\/u><\/em><em><u>\u00bb.<\/u><\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Son tambien objetivos de las presas poder almacenar grandes cantidades de agua que garantizen la disponibilidad en calidad y cantidad para contrarestar las irregularidades en las precipitaciones y, consecuentemente, en el r\u00e9gimen hidrol\u00f3gico, en zonas de elevados consumos, as\u00ed como retener y laminar los efectos negativos de las avenidas disminuyendo el riesgo de inundaciones que puedan afectar n\u00facleos urbanos, industriales, infraestructuras y servicios y ocupaciones de todo tipo vulnerables y situadas aguas abajo.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><em><strong>El equivalente en ingl\u00e9s, es \u00abdam\u00bb y se define, utilizano la misma fuente que anteriormente, como \u00abA wall built across a river to hold back the water and form a reservoir\u00bb.<\/strong><\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>4. Embalses<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Seg\u00fan la RAE se considera como embalse \u00abGran dep\u00f3sito que se forma artificialmente, por lo com\u00fan cerrando la boca de un valle mediante un <strong>dique o presa<\/strong>, y en el que se almacenan las aguas de un r\u00edo o arroyo, a fin de utilizarlas en el riego de terrenos, en el abastecimiento de poblaciones, en la producci\u00f3n de energ\u00eda el\u00e9ctrica, etc\u00e9tera.\u00bb<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Ser\u00eda por tanto el contenido, reservorio o cuerpo de agua retenido por la estructura f\u00edsica de la presa o dique, pero no la barrera en si misma.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Precisamente en ingl\u00e9s se habla de <em>\u201creservoir\u201d <\/em>como \u201c<em>A large lake where water is stored to be used by a particular area, city, etc.\u201d<\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>5. Pantanos<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>Aqu\u00ed, la RAE, en su definici\u00f3n deja clara la diferencia respecto al embalse en funci\u00f3n de su naturalidad en este caso y artificialidad en el anterior, \u00abTerreno hundido de fondo m\u00e1s o menos cenagoso y abundante vegetaci\u00f3n, donde las aguas se estancan de forma natural.\u00bb<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>Si bien es cierto que frecuentemente se han confundido conceptos, no deber\u00edan emplearse indistintamente y no confundir aguas embalsadas con aguas pantanosas.<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Los pantanos o ci\u00e9nagas son estancamientos de agua poco profundos, con alta presencia de materia prg\u00e1nica y vegetaci\u00f3n acu\u00e1tica m\u00e1s o menos frondosa, que existen en todos los continentesdel planeta, excepto en la Ant\u00e1rtida. Los pantanos pueden ser de agua dulce o de agua salada, y estar provistos o desprovistos de movimientos de marea, dependiendo del cuerpo de agua cercano que les suministre la humedad.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Son ecosistemas intermedios entre el <a href=\"https:\/\/concepto.de\/ecosistema-acuatico\/\">acu\u00e1t<\/a>ico y el <a href=\"https:\/\/concepto.de\/ecosistema-terrestre\/\">terrestre<\/a>, dotados de una <a href=\"https:\/\/concepto.de\/flora-y-fauna\/\">flora y una fa<\/a>una particulares, adaptadas a las altas condiciones de humedad que producen lodos, sedimentos y una baja concentraci\u00f3n de ox\u00edgeno en las aguas, fruto de la acumulaci\u00f3n de materia org\u00e1nica y <a href=\"https:\/\/concepto.de\/microorganismo\/\">microorganis<\/a>mos.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Traducido al ingl\u00e9s hablamos de \u00ab<em>swamp\u00bb <\/em>que significa \u00ab<em>An area of soft wet land\u00bb.<\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>6. Aspectos positivos y negativos de las infraestructuras de retenci\u00f3n y\/o derivaci\u00f3n de agua<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Dado el caracter natural de los mismos, en los pantanos no tiene sentido hablar de aspectos negativos de las infraestructuras y en principio estas masas de agua, de acuerdo con las normativas ambientales, deben mantenerse y protegerse de cambios artificiales que las puedan alterar.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Los azudes permiten que sus aguas retenidas y derivadas den satisfacci\u00f3n a los diversos, y, en su caso, leg\u00edtimos usos si estos se llevan a cabo cumpliendo las normativas, a los que se destinan dentro de la actividad humana desarrollada alrededor de los cursos de agua, pero evidentemente suponen unas alteraciones de la morfologia y din\u00e1mica fluvial natural de estos.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">As\u00ed, en ocasiones, se producen serios efectos negativos sobre la din\u00e1mica y continuidad fluvial impidiendo o dificultando la libre circulaci\u00f3n de especies de fauna acu\u00e1tica, alterando los r\u00e9gimenes de caudales tanto l\u00edquidos como s\u00f3lidos y modificando la morfologia, estructura y vegetaci\u00f3n de sus riberas naturales.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Las presas, y como ya se ha citado, permiten almacenar en sus embalses asociados grandes cantidades de agua que pueden garantizar la disponibilidad del recurso para los diferentes usos en zonas y \u00e9pocas de altas demandas y pocas aportaciones naturales, as\u00ed como en muchos casos la producci\u00f3n de energia renovable (aunque no siempre sostenible), como lo es la hidroel\u00e9ctrica, facilitando el desarrollo econ\u00f3mico y social de las zonas servidas. Al mismo tiempo pueden suponer un vital instrumento de gesti\u00f3n del riesgo de los efectos negativos por inundaciones.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Grandes zonas de regad\u00edos o el abastecimiento para consumo humano e industrial de areas fuertemente pobladas no ser\u00edan posibles sin este tipo de infraestructuras que no obstante implican unas graves y en muchos casos irreversibles alteraciones, en el sentido de lo comentado para azudes pero evidentemente en mucha mayor magnitud especialmente en lo referente a la continuidad ict\u00edcola y el r\u00e9gimen de caudales s\u00f3lidos y l\u00edquidos dificultando s\u00e9riamente los objetivos de estado de las masas de agua afectadas de acuerdo con la Directiva Marco del Agua y normativas ambientales y de protecci\u00f3n de la naturaleza concordantes.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>7. \u00bfEs posible y conveniente la demolici\u00f3n?<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Descartados los pantanos por el caracter natural de estos seg\u00fan las acepciones recogidas por la RAE, nos centraremos en los azudes y presas de acuerdo con las diferencias establecidas etre estos dos tipos de infraestructuras.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">As\u00ed mismo se valora la posibilidad y conveniencia tanto desde el punto de vista t\u00e9cnico como normativo.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">T\u00e9cnicamente, demoler un azud y revertir la funcionalidad ambiental y recuperar la continuidad fluvial no representa, en general, una gran complejidad puesto que se trata de infraestructuras de longitud variable pero de poca altura y volumen de obra civil moderado cuando no peque\u00f1o. La tecnologia y maquinaria a utilizar es muy habitual y los presupuestos asociados son asumibles econ\u00f3micamente.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Son ya numerosos los casos y en diversas cuencas en los que se han llevado a cabo este tipo de actuaciones y se dispone de muchas publicaciones t\u00e9cnicas, guias, recomendaciones y estrategias sobre la materia, como la \u00abESTRATEGIA NACIONAL DE RESTAURACI\u00d3N DE R\u00cdOS 2023 &#8211; 2030 MINISTERIO PARA LA TRANSICI\u00d3N ECOL\u00d3GICA Y EL RETO DEMOGR\u00c1FICO SECRETAR\u00cdA DE ESTADO DE MEDIO AMBIENTE Direcci\u00f3n General del Agua de julio de 2023\u00bb o la \u00abBiodiversity Strategy 2030. Barrier Removal for River Restorati\u00f3n. European Commission.December 2021\u00bb..<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Mucho m\u00e1s compleja es la aceptaci\u00f3n social de esta demolici\u00f3n por aspectos vinculados con conceptos de patrimonio hist\u00f3rico, cultural o arquitect\u00f3nico ligados adem\u00e1s con un sentimiento local de propiedad. Ello exige una intensa labor comunicativa, divulgativa, de participaci\u00f3n p\u00fablica activa y de concertaci\u00f3n social previa a cualquier intervenci\u00f3n.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Evidentemente en lo referente a presas asociadas a embalses la posible demolici\u00f3n es much\u00edsimo m\u00e1s costosa t\u00e9cnica y econ\u00f3micamente e imposible en muchos casos de llevar a cabo por los efectos sociales, de garantia de usos y de gesti\u00f3n de inundaciones.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Si entramos en los aspectos normativos debe quedar clara la voluntad legislativa sobre la prevalencia de la normativa ambiental que vale la pena recordar, por orden cronol\u00f3gico, citando aquellas que recogen espec\u00edficamente el problema de las barreras o de forma m\u00e1s gen\u00e9rica los objetivos ambientales ligados a estas.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Si bien la \u00abDIRECTIVA 2000\/60\/CE DEL PARLAMENTO EUROPEO Y DEL CONSEJO<\/p>\n\n\n\n<p class=\"eplus-wrapper\">de 23 de octubre de 2000 por la que se establece un marco comunitario de actuaci\u00f3n en el \u00e1mbito de la pol\u00edtica de aguas\u00bb no es muy expl\u00edcita en lo referente a continuidad fluvial y los azudes y presas, si que establec\u00eda ya objetivos de protecci\u00f3n, regeneraci\u00f3n y mejora de las masas de agua superficiales incompatibles en muchos casos con los impactos de aquellas infraestructuras.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>Art\u00edculo 4.<\/strong><em>Objetivos medioambientales<\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\">1. Al poner en pr\u00e1ctica los programas de medidas especificados en los planes hidrol\u00f3gicos de cuenca:<\/p>\n\n\n\n<p class=\"eplus-wrapper\">a) para las aguas superficiales<\/p>\n\n\n\n<p class=\"eplus-wrapper\">i) los Estados miembros <strong>habr\u00e1n de aplicar las medidas necesarias para prevenir el deterioro del estado de todas las masas de agua superficial<\/strong>, sin perjuicio de los apartados 6 y 7 y no obstante lo dispuesto en el apartado 8,<\/p>\n\n\n\n<p class=\"eplus-wrapper\">ii) los Estados miembros habr\u00e1n de proteger, mejorar y regenerar todas las masas de agua superficial, sin perjuicio de la aplicaci\u00f3n del inciso iii) por lo que respecta a las masas de agua artificiales y muy modificadas, conobjeto de alcanzar un buen estado de las aguas superficiales a m\u00e1s tardar quince a\u00f1os despu\u00e9s de la entrada en vigor de la presente Directiva, de conformidad con lo dispuesto en el anexo V, sin perjuicio de la aplicaci\u00f3n de las pr\u00f3rrogas establecidas de conformidad con el apartado 3, de la aplicaci\u00f3n de los apartados 4, 5 y 6 y no obstante lo dispuesto en el apartado 7,<\/p>\n\n\n\n<p class=\"eplus-wrapper\">iii) los Estados miembros <strong>proteger\u00e1n y mejorar\u00e1n todas las masas de agua artificiales y muy modificadas, con objeto de lograr un buen potencial ecol\u00f3gico y un buen estado qu\u00edmico de las aguas superficiales<\/strong> a m\u00e1s tardar quince a\u00f1os despu\u00e9s de la entrada en vigor de la presente Directiva, de conformidad con lo dispuesto en el anexo V, sin perjuicio de la aplicaci\u00f3n de las pr\u00f3rrogas establecidas de conformidad con el apartado 4 y de la aplicaci\u00f3n de los apartados 5, 6 y 7 y no obstante lodispuesto en el apartado 8.\u00bb<\/p>\n\n\n\n<p class=\"eplus-wrapper\">As\u00ed mismo, en la \u00abLey 42\/2007, de 13 de diciembre, del Patrimonio Natural y de la Biodiversidad.\u00bb se establecen una serie de principios que, aunque no mencionan tampoco expl\u00edcitamente el tema, si que afectan a los objetivos de estas actuaciones pero que muchos no han le\u00eddo y muchos menos los han aplicado hasta ahora.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>Art\u00edculo 2. <\/strong><em>Principios.<\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Son principios que inspiran esta ley:<\/p>\n\n\n\n<p class=\"eplus-wrapper\">a) El mantenimiento de los procesos ecol\u00f3gicos esenciales y de los sistemas vitales b\u00e1sicos, respaldando los servicios de los ecosistemas para el bienestar humano.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">b) La conservaci\u00f3n y restauraci\u00f3n de la biodiversidad y de la geodiversidad mediante la conservaci\u00f3n de los h\u00e1bitats naturales y de la fauna y flora silvestres. Las medidas que se adopten para ese fin tendr\u00e1n en cuenta las exigencias econ\u00f3micas, sociales y culturales, as\u00ed como las particularidades regionales y locales.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">c) La utilizaci\u00f3n ordenada de los recursos para garantizar el aprovechamiento sostenible del patrimonio natural, en particular, de las especies y de los ecosistemas, su conservaci\u00f3n, restauraci\u00f3n y mejora y evitar la p\u00e9rdida neta de biodiversidad.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">d) La conservaci\u00f3n y preservaci\u00f3n de la variedad, singularidad y belleza de los ecosistemas naturales, de la diversidad geol\u00f3gica y del paisaje.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">e) La integraci\u00f3n de los requisitos de la conservaci\u00f3n, uso sostenible, mejora y restauraci\u00f3n del patrimonio natural y la biodiversidad en las pol\u00edticas sectoriales y, en particular, en la toma de decisiones en el \u00e1mbito pol\u00edtico, econ\u00f3mico y social, as\u00ed como la participaci\u00f3n justa y equitativa en el reparto de beneficios que se deriven de la utilizaci\u00f3n de los recursos gen\u00e9ticos.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><em><u><strong>f) La prevalencia de la protecci\u00f3n ambiental <\/strong><\/u><\/em>sobre la ordenaci\u00f3n territorial y urban\u00edstica y los supuestos b\u00e1sicos de dicha prevalencia.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">g) La precauci\u00f3n en las intervenciones que puedan afectar a espacios naturales o especies silvestres.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">h) La garant\u00eda de la informaci\u00f3n a la ciudadan\u00eda y concienciaci\u00f3n sobre la importancia de la biodiversidad, as\u00ed como su participaci\u00f3n en el dise\u00f1o y ejecuci\u00f3n de las pol\u00edticas p\u00fablicas, incluida la elaboraci\u00f3n de disposiciones de car\u00e1cter general, dirigidas a la consecuci\u00f3n de los objetivos de esta ley.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">i) La prevenci\u00f3n de los problemas emergentes consecuencia del cambio clim\u00e1tico, la mitigaci\u00f3n y adaptaci\u00f3n al mismo, as\u00ed como la lucha contra sus efectos adversos.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">j) La contribuci\u00f3n de los procesos de mejora en la sostenibilidad del desarrollo asociados a espacios naturales o seminaturales.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">k) La participaci\u00f3n de los habitantes y de los propietarios de los territorios incluidos en espacios protegidos en las actividades coherentes con la conservaci\u00f3n del patrimonio natural y de la biodiversidad que se desarrollen en dichos espacios y en los beneficios que se deriven de ellas.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">l) El mantenimiento y la adaptaci\u00f3n de las poblaciones de todas las especies de aves que viven normalmente en estado salvaje en un nivel que corresponda en particular a las exigencias ecol\u00f3gicas, cient\u00edficas y culturales, habida cuenta de las exigencias econ\u00f3micas y recreativas.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">El \u00abReal Decreto 849\/1986, de 11 de abril, por el que se aprueba el Reglamento del Dominio P\u00fablico Hidr\u00e1ulico, que desarrolla los t\u00edtulos preliminar I, IV, V, VI y VII de la Ley 29\/1985, de 2 de agosto, de Aguas\u00bb, con sus sucesivas modificaciones,las \u00faltimas en 2023, trata espec\u00edficamente la cuesti\u00f3n de las posibles demoliciones de estas barreras cuando van asociadas a concesiones de aprovechamientos.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>Art\u00edculo 89.<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\"><em>4. Al extinguirse el derecho concesional revertir\u00e1n al Estado gratuitamente y libres de cargas cuantas obras hubieran sido construidas dentro del dominio p\u00fablico hidr\u00e1ulico para la explotaci\u00f3n del aprovechamiento, sin perjuicio del cumplimiento de las condiciones estipuladas en el documento concesional y, en su caso, las relativas a la reversi\u00f3n de otros elementos situados fuera del demanio.<\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\"><em>Si en dicho momento, la Administraci\u00f3n hidr\u00e1ulica considerase posible y conveniente la continuidad del aprovechamiento, podr\u00e1 exigir del concesionario la entrega de los bienes objeto de reversi\u00f3n en condiciones de explotaci\u00f3n tal como prev\u00e9n los art\u00edculos 164.3, 165.3 y 167.3 y 4. Si por el contrario lo considerase inviable, o su mantenimiento resultase contrario al inter\u00e9s p\u00fablico, podr\u00e1 exigir la demolici\u00f3n de lo construido en dominio p\u00fablico de conformidad con el art\u00edculo 101 de la Ley 33\/2003, de 3 de noviembre, del Patrimonio de las Administraciones P\u00fablicas.<\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>Art\u00edculo 126 bis. <\/strong>Condiciones para garantizar la continuidad fluvial.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><em>4. <\/em><em><u><strong>El organismo de cuenca promover\u00e1 la eliminaci\u00f3n de infraestructuras que, dentro del dominio p\u00fablico hidr\u00e1ulico, se encuentren abandonadas sin cumplir funci\u00f3n alguna ligada al aprovechamiento de las aguas,<\/strong><\/u><\/em><em> teniendo en consideraci\u00f3n la seguridad de las personas y los bienes y valorando el efecto ambiental y econ\u00f3mico de cada actuaci\u00f3n.<\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\">M\u00e1s recientemente el \u00ab<strong>REGLAMENTO (UE) 2024\/1991 DEL PARLAMENTO EUROPEO Y DEL CONSEJO de 24 de junio de 2024 relativo a la restauraci\u00f3n de la naturaleza y por el que se modifica el Reglamento (UE) 2022\/869\u00bb <\/strong>si que recoge tambi\u00e9n directamente la problem\u00e1tica de las barreras artificiales (azudes, presas&#8230;).<\/p>\n\n\n\n<h5 class=\"wp-block-heading eplus-wrapper\">Art\u00edculo 9. Restauraci\u00f3n de la conectividad natural de los r\u00edos y de las funciones naturales de las llanuras aluviales correspondientes<\/h5>\n\n\n\n<p class=\"eplus-wrapper\">1. Los Estados miembros elaborar\u00e1n un inventario de las barreras artificiales a la conectividad de las aguas superficiales y, teniendo en cuenta las funciones socioecon\u00f3micas de las barreras artificiales, determinar\u00e1n las barreras que deban eliminarse para contribuir a la consecuci\u00f3n de los objetivos de restauraci\u00f3n establecidos en el art\u00edculo 4 del presente Reglamento, y al cumplimiento del objetivo de restaurar al menos 25.000 km de r\u00edos en la Uni\u00f3n para que vuelvan a ser de flujo libre de aqu\u00ed a 2030, sin perjuicio de lo dispuesto en la Directiva 2000\/60\/CE, en particular su art\u00edculo 4, apartados 3, 5 y7, y en el Reglamento (UE) n.o 1315\/2013 del Parlamento Europeo y del Consejo (46), en particular su art\u00edculo 15.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><em><u><strong>2. Los Estados miembros eliminar\u00e1n las barreras artificiales a la conectividad de las aguas superficiales determinadas en el inventario elaborado con arreglo al apartado 1 del presente art\u00edculo, de conformidad con el plan para su eliminaci\u00f3n a que se refiere el art\u00edculo 15, apartado 3, letras i) y n). Al eliminar las barreras artificiales, los Estados miembros deben ocuparse principalmente de las barreras obsoletas, a saber, aquellas que hayan dejado de ser necesarias para la generaci\u00f3n de energ\u00edas renovables, la navegaci\u00f3n interior, el suministro de agua, la protecci\u00f3n frente a las inundaciones u otros usos.<\/strong><\/u><\/em><\/p>\n\n\n\n<p class=\"eplus-wrapper\">3. Los Estados miembros complementar\u00e1n la eliminaci\u00f3n de las barreras artificiales de acuerdo con el apartado 2 con las medidas necesarias para mejorar las funciones naturales de las llanuras aluviales correspondientes.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">4. Los Estados miembros garantizar\u00e1n que se mantenga la conectividad natural de los r\u00edos y las funciones naturales de las llanuras aluviales restauradas de conformidad con los apartados 2 y 3.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Queda clara pues la voluntad legislativa, en diferentes \u00e1mbitos y niveles, de mejorar el estado de las masas de agua y de la eliminaci\u00f3n de aquellas barreras que puedan ser un obst\u00e1culo a este objetivo.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><strong>8. Conclusiones<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\">Quedan claras, tanto en espa\u00f1ol como en ingl\u00e9s, las diferencias entre los diversos conceptos de; azudes, presas, embalses y pantanos, por lo que deber\u00edamos utilizarlos de acuerdo con ellos.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Existe legislaci\u00f3n suficiente que avala la demolici\u00f3n, o en su caso permeabilizaci\u00f3n, de infraestucturas en desuso u obsoletas que suponen barreras a la continuidad fluvial y a los objetivos ambientales de estas actuaciones y espec\u00edficamente y sobre todo diversos art\u00edculos del <strong>Reglamento europeo relativo a la restauraci\u00f3n de la naturaleza <\/strong>y del <strong>Reglamento del Dominio P\u00fablico Hidr\u00e1ulico.<\/strong><\/p>\n\n\n\n<p class=\"eplus-wrapper\">La eliminaci\u00f3n de barreras como los azudes (denominados tambi\u00e9n comunmente \u00abpeque\u00f1as presas\u00bb), es t\u00e9cnica y econ\u00f3micamente factible y se dispone de suficiente apoyo cient\u00edfico y t\u00e9cnico.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Estas demoliciones no solamente son una posibilidad, sin\u00f3 que son un mandamiento para los organismos de cuenca en su funci\u00f3n de aplicaci\u00f3n de la normativa vigente en materia hidr\u00e1ulica y ambiental al objeto de mejorar el estado de las masas de agua y ecosistemas naturales asociados.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">La normativa, el conocimiento t\u00e9cnico y cient\u00edfico, y las correctas definiciones terminol\u00f3gicas, suponen un respaldo a las entidades p\u00fablicas, sociales y ambientales que las promueven frente a las posiciones negacionistas y mensajes distorsionados o simplemente falsos.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Ante cualquier posible actuaci\u00f3n de demolici\u00f3n de estas barreras, debe promoverse, pr\u00e9viamente, una participaci\u00f3n p\u00fablica activa y de concertaci\u00f3n social con todos los agentes implicados y en especial en el \u00e1mbito local afectado.<\/p>\n\n\n\n<p class=\"eplus-wrapper\"><\/p>","protected":false},"excerpt":{"rendered":"<p>1. Introducci\u00f3n Es frecuente, desgraciadamente, que en determinados medios de comunicaci\u00f3n, redes sociales e incluso en algunos foros presuntamente t\u00e9cnicos, se hable sin demasiado rigor de todas estas infraestructuras (en el caso de pantanos, tipo de terreno), y sus possibles demoliciones confundiendo conceptos y obviando frecuentemente lo contemplado por las normativas vigentes en especial en &#8230; <a title=\"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones.\" class=\"read-more\" href=\"https:\/\/cirefluvial.com\/en\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/\" aria-label=\"Read more about Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones.\">Read more<\/a><\/p>","protected":false},"author":1,"featured_media":7261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[1,9],"tags":[],"class_list":["post-7885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-noticias","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"gutentor_comment":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones. - CIREF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cirefluvial.com\/en\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones. - CIREF\" \/>\n<meta property=\"og:description\" content=\"1. Introducci\u00f3n Es frecuente, desgraciadamente, que en determinados medios de comunicaci\u00f3n, redes sociales e incluso en algunos foros presuntamente t\u00e9cnicos, se hable sin demasiado rigor de todas estas infraestructuras (en el caso de pantanos, tipo de terreno), y sus possibles demoliciones confundiendo conceptos y obviando frecuentemente lo contemplado por las normativas vigentes en especial en ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cirefluvial.com\/en\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/\" \/>\n<meta property=\"og:site_name\" content=\"CIREF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-21T17:38:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T17:38:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2025\/06\/02-Zuniga-despues-pichi-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fixer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Cirefluvial\" \/>\n<meta name=\"twitter:site\" content=\"@Cirefluvial\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"fixer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/\"},\"author\":{\"name\":\"fixer\",\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/person\/8e24d361e4490b3110a8a67807daa411\"},\"headline\":\"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones.\",\"datePublished\":\"2026-01-21T17:38:28+00:00\",\"dateModified\":\"2026-01-21T17:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/\"},\"wordCount\":3475,\"publisher\":{\"@id\":\"https:\/\/cirefluvial.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2025\/06\/02-Zuniga-despues-pichi-1.jpg\",\"articleSection\":[\"Blog\",\"Noticias\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/\",\"url\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/\",\"name\":\"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones. - CIREF\",\"isPartOf\":{\"@id\":\"https:\/\/cirefluvial.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2025\/06\/02-Zuniga-despues-pichi-1.jpg\",\"datePublished\":\"2026-01-21T17:38:28+00:00\",\"dateModified\":\"2026-01-21T17:38:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#primaryimage\",\"url\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2025\/06\/02-Zuniga-despues-pichi-1.jpg\",\"contentUrl\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2025\/06\/02-Zuniga-despues-pichi-1.jpg\",\"width\":1240,\"height\":697,\"caption\":\"02-Zun\u0303iga-despues\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/cirefluvial.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cirefluvial.com\/#website\",\"url\":\"https:\/\/cirefluvial.com\/\",\"name\":\"CIREF\",\"description\":\"Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial\",\"publisher\":{\"@id\":\"https:\/\/cirefluvial.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cirefluvial.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cirefluvial.com\/#organization\",\"name\":\"Centro Iberico de Restauraci\u00f3n Fluvial\",\"url\":\"https:\/\/cirefluvial.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png\",\"contentUrl\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png\",\"width\":212,\"height\":80,\"caption\":\"Centro Iberico de Restauraci\u00f3n Fluvial\"},\"image\":{\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/\",\"https:\/\/x.com\/Cirefluvial\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/person\/8e24d361e4490b3110a8a67807daa411\",\"name\":\"fixer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g\",\"caption\":\"fixer\"},\"sameAs\":[\"https:\/\/cirefluvial.com\"],\"url\":\"https:\/\/cirefluvial.com\/en\/author\/fixer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones. - CIREF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cirefluvial.com\/en\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/","og_locale":"en_GB","og_type":"article","og_title":"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones. - CIREF","og_description":"1. Introducci\u00f3n Es frecuente, desgraciadamente, que en determinados medios de comunicaci\u00f3n, redes sociales e incluso en algunos foros presuntamente t\u00e9cnicos, se hable sin demasiado rigor de todas estas infraestructuras (en el caso de pantanos, tipo de terreno), y sus possibles demoliciones confundiendo conceptos y obviando frecuentemente lo contemplado por las normativas vigentes en especial en ... Read more","og_url":"https:\/\/cirefluvial.com\/en\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/","og_site_name":"CIREF","article_publisher":"https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/","article_published_time":"2026-01-21T17:38:28+00:00","article_modified_time":"2026-01-21T17:38:29+00:00","og_image":[{"width":1240,"height":697,"url":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2025\/06\/02-Zuniga-despues-pichi-1.jpg","type":"image\/jpeg"}],"author":"fixer","twitter_card":"summary_large_image","twitter_creator":"@Cirefluvial","twitter_site":"@Cirefluvial","twitter_misc":{"Written by":"fixer","Estimated reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#article","isPartOf":{"@id":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/"},"author":{"name":"fixer","@id":"https:\/\/cirefluvial.com\/#\/schema\/person\/8e24d361e4490b3110a8a67807daa411"},"headline":"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones.","datePublished":"2026-01-21T17:38:28+00:00","dateModified":"2026-01-21T17:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/"},"wordCount":3475,"publisher":{"@id":"https:\/\/cirefluvial.com\/#organization"},"image":{"@id":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#primaryimage"},"thumbnailUrl":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2025\/06\/02-Zuniga-despues-pichi-1.jpg","articleSection":["Blog","Noticias"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/","url":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/","name":"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones. - CIREF","isPartOf":{"@id":"https:\/\/cirefluvial.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#primaryimage"},"image":{"@id":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#primaryimage"},"thumbnailUrl":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2025\/06\/02-Zuniga-despues-pichi-1.jpg","datePublished":"2026-01-21T17:38:28+00:00","dateModified":"2026-01-21T17:38:29+00:00","breadcrumb":{"@id":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#primaryimage","url":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2025\/06\/02-Zuniga-despues-pichi-1.jpg","contentUrl":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2025\/06\/02-Zuniga-despues-pichi-1.jpg","width":1240,"height":697,"caption":"02-Zun\u0303iga-despues"},{"@type":"BreadcrumbList","@id":"https:\/\/cirefluvial.com\/sobre-la-demolicion-de-barreras-azudes-presas-y-pantanos-aclarando-terminos-y-cuestiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cirefluvial.com\/"},{"@type":"ListItem","position":2,"name":"Sobre la demolici\u00f3n de barreras, azudes, presas y pantanos. Aclarando t\u00e9rminos y cuestiones."}]},{"@type":"WebSite","@id":"https:\/\/cirefluvial.com\/#website","url":"https:\/\/cirefluvial.com\/","name":"CIREF","description":"Iberian Centre for River Restoration","publisher":{"@id":"https:\/\/cirefluvial.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cirefluvial.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cirefluvial.com\/#organization","name":"Centro Iberico de Restauraci\u00f3n Fluvial","url":"https:\/\/cirefluvial.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/","url":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png","contentUrl":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png","width":212,"height":80,"caption":"Centro Iberico de Restauraci\u00f3n Fluvial"},"image":{"@id":"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/","https:\/\/x.com\/Cirefluvial"]},{"@type":"Person","@id":"https:\/\/cirefluvial.com\/#\/schema\/person\/8e24d361e4490b3110a8a67807daa411","name":"fixer","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cirefluvial.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g","caption":"fixer"},"sameAs":["https:\/\/cirefluvial.com"],"url":"https:\/\/cirefluvial.com\/en\/author\/fixer\/"}]}},"_links":{"self":[{"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/posts\/7885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/comments?post=7885"}],"version-history":[{"count":1,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/posts\/7885\/revisions"}],"predecessor-version":[{"id":7886,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/posts\/7885\/revisions\/7886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/media\/7261"}],"wp:attachment":[{"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/media?parent=7885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/categories?post=7885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/tags?post=7885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}