{"id":6451,"date":"2024-11-13T12:06:43","date_gmt":"2024-11-13T11:06:43","guid":{"rendered":"https:\/\/cirefluvial.com\/?p=6451"},"modified":"2024-11-14T17:05:57","modified_gmt":"2024-11-14T16:05:57","slug":"consideraciones-sobre-la-dana-del-29-deoctubre-de-2024","status":"publish","type":"post","link":"https:\/\/cirefluvial.com\/en\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/","title":{"rendered":"Consideraciones sobre la DANA del 29 de octubre de 2024,"},"content":{"rendered":"<p class=\"has-accent-color has-text-color has-link-color wp-elements-0a7da8dc6f52a6dbd951236cf35f1fa3\"><strong>En relaci\u00f3n con la cat\u00e1strofe asociada a la DANA del 29 de octubre de 2024, el CIREF quiere destacar y manifestar las siguientes consideraciones<\/strong>:<\/p>\n\n\n\n<p>Ante todo, desde el Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial (CIREF), queremos manifestar nuestra m\u00e1xima solidaridad, afecto y cari\u00f1o para con todas las personas afectadas por la tragedia que se ha originado a ra\u00edz de la reciente DANA acontecida entre finales de octubre y principios de noviembre de 2024. Especialmente con las v\u00edctimas y sus familiares, pero tambi\u00e9n con todas aquellas personas voluntarias, pertenecientes a diferentes ONGs y profesionales de diferentes cuerpos y administraciones del Estado y de la Comunitat Valenciana y otras Comunidades Aut\u00f3nomas tambi\u00e9n afectadas, que han trabajado y siguen trabajando actualmente en la atenci\u00f3n a los damnificados y en recuperar la normalidad lo antes posible. Por todas ellas pensamos que merece la pena aportar nuestro an\u00e1lisis sosegado y cient\u00edfico-t\u00e9cnico a este tipo de situaciones, con el objetivo m\u00e1ximo de contribuir a una mayor capacitaci\u00f3n de la poblaci\u00f3n que le permita combatir la desinformaci\u00f3n, y de alertar a las administraciones para que situaciones como esta no se repitan con unas consecuencias tan graves en el futuro.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a045faa91a49&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a045faa91a49\" class=\"wp-block-image size-full wp-lightbox-container\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"752\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg\" alt=\"\" class=\"wp-image-6459\" srcset=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg 1000w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi-300x226.jpg 300w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi-768x578.jpg 768w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi-50x38.jpg 50w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi-16x12.jpg 16w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">R\u00edo Magro (6\/11\/2024) \u00a9\ufe0fFrancisco Mart\u00ednez-Capel<\/figcaption><\/figure>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-accent-color has-text-color has-link-color wp-elements-25af437b165008324489346ba96cb40d\">LO QUE HA PASADO<\/h4>\n\n\n\n<p>Una DANA intensa, estabilizada en media Pen\u00ednsula y alimentada por un Mediterr\u00e1neo recalentado ha generado unas lluvias de gran volumen e intensidad en diferentes territorios, alcanzando valores m\u00e1ximos en el interior de la provincia de Valencia. Desde ah\u00ed, los r\u00edos, barrancos y ramblas han hecho su trabajo de evacuar el agua y el sedimento hasta el mar. Y las llanuras inundables han hecho tambi\u00e9n su trabajo de ensanchar el proceso, disipar su energ\u00eda y almacenar agua temporalmente. Un proceso natural normal, aunque haya sido con valores extremos, como otros que se produjeron a lo largo de la historia y otros que se producir\u00e1n. Un proceso natural necesario para el equilibrio planetario y su salud global, para reajustar el equilibrio atmosf\u00e9rico con el equilibrio hidrogeomorfol\u00f3gico terrestre y marino.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-accent-color has-text-color has-link-color wp-elements-1e74d0e0faad5004a4448312827f77a0\">UN CAMBIO DE PARADIGMA<\/h4>\n\n\n\n<p>Un proceso natural de estas caracter\u00edsticas y de esta magnitud, e incluso mayor, es previsible que se registre en el futuro con mayor frecuencia en la Pen\u00ednsula, como consecuencia del cambio clim\u00e1tico antropog\u00e9nico que nos ha ido llevando a temperaturas cada vez m\u00e1s elevadas, que no se ha frenado y que nos impulsa a fen\u00f3menos extremos cada vez m\u00e1s frecuentes. Esta previsi\u00f3n, avalada por numerosos estudios cient\u00edficos, requerir\u00e1 cambios importantes en la actividad y el asentamiento humano, que deber\u00e1n regirse de forma urgente y creciente por los principios de humildad, prevenci\u00f3n y adaptaci\u00f3n. <\/p>\n\n\n\n<p>Podr\u00edamos aventurar que procesos clim\u00e1ticos extremos como este, est\u00e1n entrando ya en un nuevo terreno\/paradigma, m\u00e1s similar al Vulcanismo. Es decir, procesos que no se pueden contener de forma eficaz con infraestructuras y para los que las \u00fanicas medidas eficaces ante ellos son retirar de su alcance los asentamientos, y evacuar con rapidez y eficacia a la poblaci\u00f3n que permanezca. Ser\u00e1 por tanto muy importante mejorar y profundizar en todo lo relacionado con la prevenci\u00f3n, capacitando a la poblaci\u00f3n e incluso desarrollar simulacros en zonas con especial riesgo. <\/p>\n\n\n\n<h4 class=\"wp-block-heading has-accent-color has-text-color has-link-color wp-elements-7fc0c365edb4bd5a4ac6d9f42dd3d030\">LAS CONSECUENCIAS <\/h4>\n\n\n\n<p><strong>Los da\u00f1os de la cat\u00e1strofe son en su totalidad responsabilidad humana, por exposici\u00f3n y vulnerabilidad, en una zona muy urbanizada y no adaptada a los procesos naturales extremos<\/strong>, ni siquiera en condiciones clim\u00e1ticas normales. La propia urbanizaci\u00f3n impermeabiliza el terreno, sumando lo que llueve in situ a los caudales, y los cimientos y garajes subterr\u00e1neos que ocupan el aluvial empujan m\u00e1s agua a superficie. Todo esto convierte en sin\u00e9rgicas los tres tipos de inundaciones habituales: inundaciones pluviales (ocurre cuando un evento de lluvia extrema crea una inundaci\u00f3n independientemente de que haya un cuerpo de agua desbordado), inundaciones fluviales (o inundaci\u00f3n de r\u00edo) y fre\u00e1ticas (cuando se produce una subida excepcional del nivel de la capa&nbsp;fre\u00e1tica&nbsp;m\u00e1s cercana al suelo). <\/p>\n\n\n\n<p>El arrastre de sedimentos, fruto de una erosi\u00f3n que en ocasiones tambi\u00e9n se ve incrementada m\u00e1s all\u00e1 de lo que ser\u00eda natural por la deforestaci\u00f3n o degradaci\u00f3n del territorio de la cuenca, unido al arrastre de materia vegetal de especies invasoras como las ca\u00f1as (Arundo donax), veh\u00edculos, enseres, etc., incrementan los vol\u00famenes y la capacidad de generar da\u00f1os de los flujos de agua. <\/p>\n\n\n\n<p>A su vez, los puentes mal dimensionados, las v\u00edas de comunicaci\u00f3n y otras infraestructuras instaladas en las llanuras inundables han alterado los flujos y han conducido y agravado el problema hacia zonas concretas. Existen calles, viviendas, residencias de mayores, centros educativos, servicios p\u00fablicos b\u00e1sicos en \u00e1reas de m\u00e1xima inundabilidad. <\/p>\n\n\n\n<p>Se sab\u00eda que esto iba a pasar, porque nuestras poblaciones se han venido desarrollado sin la ordenaci\u00f3n territorial y planificaci\u00f3n urban\u00edstica adecuadas en las \u00faltimas d\u00e9cadas, anteponiendo los intereses econ\u00f3micos a la prudencia. Esto podr\u00eda haber pasado en otros lugares y lamentablemente lo har\u00e1 en el futuro, pues hoy en d\u00eda disponemos de herramientas, cartograf\u00eda de zonas inundables, estudios de riesgos, estudios sobre los efectos del cambio clim\u00e1tico, etc., que nos permiten ser muy conscientes de que buena parte de nuestros territorios no est\u00e1n adaptados y son altamente vulnerables, en resumen, se conocen los riesgos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a045faa92cc3&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a045faa92cc3\" class=\"wp-block-image size-full is-style-default wp-lightbox-container\"><img decoding=\"async\" width=\"1000\" height=\"562\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"6463\" src=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-3-pichi.jpg\" alt=\"Barranco del pollo\" class=\"wp-image-6463\" srcset=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-3-pichi.jpg 1000w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-3-pichi-300x169.jpg 300w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-3-pichi-768x432.jpg 768w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-3-pichi-50x28.jpg 50w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-3-pichi-18x10.jpg 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Vista del barranco del Pollo en Pica\u00f1a (7\/11\/2024) \u00a9\ufe0fFrancisco Mart\u00ednez-Capel<\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a045faa9368a&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a045faa9368a\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1000\" height=\"562\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"6462\" src=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-2-pichi.jpg\" alt=\"Barranco del pollo\" class=\"wp-image-6462\" srcset=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-2-pichi.jpg 1000w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-2-pichi-300x169.jpg 300w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-2-pichi-768x432.jpg 768w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-2-pichi-50x28.jpg 50w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-pollo-2-pichi-18x10.jpg 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">El barranco del Pollo y viviendas destruidas a su lado, desde Pica\u00f1a (7\/11\/2024) \u00a9\ufe0fFrancisco Mart\u00ednez-Capel<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-accent-color has-text-color has-link-color wp-elements-5194d915c5cffd04546c6f0bcd16332d\">LAS SOLUCIONES <\/h4>\n\n\n\n<p>Hay que considerar que la situaci\u00f3n actual de muchos territorios, agravada por el cambio clim\u00e1tico y las nuevas infraestructuras que vamos construyendo, nos deber\u00eda llevar a tener que actualizar la cartograf\u00eda de los espacios inundables con frecuencia y a reevaluar el riesgo de forma continua; pensemos que la mayor frecuencia e intensidad de los eventos esperables implican: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reducciones claras de los periodos de retorno (n\u00famero de a\u00f1os que, en t\u00e9rminos medios, pasa entre dos presentaciones sucesivas de un determinado suceso 1 ) <\/li>\n\n\n\n<li>Aumentos en flujos (el caudal volum\u00e9trico de agua que pasa por un punto determinado de un r\u00edo), y calados (altura que alcanza la superficie del agua sobre el fondo) <\/li>\n\n\n\n<li>Mayor extensi\u00f3n en cauces y espacios inundables. <\/li>\n<\/ul>\n\n\n\n<p>Medidas de soluci\u00f3n o para paliar los efectos y riesgos: <\/p>\n\n\n\n<p>Afrontar de forma radicalmente diferente la ordenaci\u00f3n del territorio y el urbanismo en espacios inundables, reordenando los usos del suelo y dejando la mayor parte de la superficie y del subsuelo para la expansi\u00f3n y la laminaci\u00f3n natural de estos procesos extremos, es decir, desocupando todo lo posible las zonas inundables. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fomentar la descanalizaci\u00f3n y los encauzamientos all\u00e1 donde sea posible, para dar m\u00e1s espacio a los cauces y reducir as\u00ed su energ\u00eda, velocidad y capacidad destructiva, y para poder reconectar los cauces con sus llanuras de inundaci\u00f3n, verdaderos recintos naturales de laminaci\u00f3n. <\/li>\n\n\n\n<li>Proceder a la desurbanizaci\u00f3n o retirada de construcciones e infraestructuras vulnerables con riesgo para las personas. <\/li>\n\n\n\n<li>Adaptar los edificios en zonas inundables que tengan que seguir ah\u00ed suprimiendo o inhabilitando plantas s\u00f3tano y bajas. <\/li>\n\n\n\n<li>Redimensionar puentes y otras infraestructuras, y seguir eliminando, con m\u00e1xima urgencia e intensidad, azudes, barreras, vados y obst\u00e1culos innecesarios u obsoletos de todo tipo, que impidan la adecuada funci\u00f3n de laminaci\u00f3n e infiltraci\u00f3n de los cauces. <\/li>\n\n\n\n<li>Aplicar sistemas de drenaje urbano sostenible para tener \u201cciudades esponja\u201d, y mejorar las condiciones en casos de fuertes precipitaciones no asociadas a desbordamientos, ya que reducen la escorrent\u00eda pluvial, que es el agua de lluvia no absorbida por la superficie urbana. <\/li>\n\n\n\n<li>Olvidarse del hormig\u00f3n como \u00fanica soluci\u00f3n y de los planes de defensa basados en encauzamientos de los r\u00edos del pasado. Es posible que deban mantenerse o mejorarse algunos tramos encauzados en zonas urbanas consolidadas, pero en ning\u00fan caso generalizar esta soluci\u00f3n para otras zonas y tramos fluviales donde se ha demostrado que estas soluciones no han hecho m\u00e1s que incrementar los problemas y da\u00f1os.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size\"> 1 Es el inverso de la probabilidad de que un suceso ocurra durante un a\u00f1o dado. As\u00ed, una avenida de un periodo de retorno de 100 a\u00f1os es aqu\u00e9lla que en un a\u00f1o dado tiene una probabilidad de suceder del 1%.<\/p>\n\n\n\n<p><strong>Debemos optar, en suma, por soluciones inteligentes basadas en la naturaleza, que la imiten, que nos adapten a ella y que se adapten lo mejor posible a cada casu\u00edstica y territorio.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a045faa95ac3&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a045faa95ac3\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"6478\" src=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-12.01.35-pichi.jpg\" alt=\"\" class=\"wp-image-6478\" srcset=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-12.01.35-pichi.jpg 1000w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-12.01.35-pichi-300x225.jpg 300w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-12.01.35-pichi-768x576.jpg 768w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-12.01.35-pichi-50x38.jpg 50w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-12.01.35-pichi-16x12.jpg 16w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Barranco del Pollo en Pican\u0303a -\u00a9\ufe0fEmilia Climent<\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a045faa98961&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a045faa98961\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"562\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"6470\" src=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-11.36.54-pichi.jpg\" alt=\"\" class=\"wp-image-6470\" srcset=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-11.36.54-pichi.jpg 1000w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-11.36.54-pichi-300x169.jpg 300w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-11.36.54-pichi-768x432.jpg 768w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-11.36.54-pichi-50x28.jpg 50w, https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-13-at-11.36.54-pichi-18x10.jpg 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Aspecto de las v\u00edas de tren que separan Pica\u00f1a y Paiporta (7\/11\/2024) \u00a9\ufe0fFrancisco Mart\u00ednez-Capel<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-accent-color has-text-color has-link-color wp-elements-97a44300741fc4f441112d56915103a1\">EL FUTURO HA DE HACERSE PRESENTE <\/h4>\n\n\n\n<p>La geograf\u00eda, la geolog\u00eda, la ecolog\u00eda, las ciencias ambientales, las ciencias sociales, las ingenier\u00edas y la arquitectura cuentan con muchos conocimientos que aportar y deber\u00edan intervenir much\u00edsimo m\u00e1s en la toma de decisiones. Tienen que contribuir a una nueva ordenaci\u00f3n del territorio, a la devoluci\u00f3n a los r\u00edos de su espacio, a una nueva forma de construir y a una nueva forma de vivir en donde prime la salud y el bienestar sobre el capital. <\/p>\n\n\n\n<p>Tambi\u00e9n por ello es preciso y urgente aumentar los sistemas de alerta temprana de crecidas, sobre todo en cuencas de r\u00e9gimen torrencial con muy escasas estaciones de aforo hasta ahora. En esta l\u00ednea, es imprescindible asociar las alertas meteorol\u00f3gicas a las hidrol\u00f3gicas y generar un mecanismo m\u00e1s r\u00e1pido para emitir alertas sociales que sean taxativas y contundentes, sin ninguna excepci\u00f3n, e impidan da\u00f1os personales. <\/p>\n\n\n\n<p>Y en este sentido, debe tambi\u00e9n avanzarse en la divulgaci\u00f3n y concienciaci\u00f3n de la poblaci\u00f3n, y en la elaboraci\u00f3n de protocolos y simulacros para que todo el mundo sepa lo que hay que hacer. Sin olvidar que, seg\u00fan los criterios de la Directiva de Inundaciones 2007\/60\/CE y Real Decreto 903\/2010, de evaluaci\u00f3n y gesti\u00f3n de riesgos de inundaci\u00f3n, los municipios catalogados como <strong>\u00c1reas con Riesgo Potencial Significativo de Inundaci\u00f3n (ARPSI<\/strong>) deben elaborar su Plan de Actuaci\u00f3n Municipal correspondiente. Los simulacros permiten validar y ajustar dichos Planes, as\u00ed como el funcionamiento de sus Sistemas de Alerta Temprana. <\/p>\n\n\n\n<p>La reciente cat\u00e1strofe acaecida en Valencia, sobre todo, as\u00ed como en otras zonas de Castilla-La Mancha y Andaluc\u00eda, es principalmente a consecuencia de priorizar la econom\u00eda frente a la seguridad y a la salud de las personas, de la creencia de que nuestras capacidades tecnol\u00f3gicas est\u00e1n por encima del devenir de la naturaleza y tambi\u00e9n, no siempre pero lamentablemente en bastantes ocasiones, de la incompetencia, falta de coordinaci\u00f3n y eficacia de las administraciones, todo ello agravado por el cambio clim\u00e1tico. <\/p>\n\n\n\n<p>Nuestro reconocimiento y gratitud a los mecanismos de previsi\u00f3n, la AEMET y el SAIH (Sistemas Autom\u00e1ticos de Informaci\u00f3n Hidrol\u00f3gica gestionado por las Confederaci\u00f3n Hidrogr\u00e1ficas), por sus certeras y r\u00e1pidas predicciones, a los servicios de emergencia, protecci\u00f3n civil, la UME, fuerzas de seguridad y orden p\u00fablico, as\u00ed como al voluntariado que, aun cuando redactamos esta nota se dejan la piel en ayudar a las personas y devolver cuanto antes la normalidad a las zonas afectadas. Nuestra reprobaci\u00f3n a la irresponsabilidad pol\u00edtica que, con dram\u00e1ticas consecuencias, retras\u00f3 y minimiz\u00f3 las alertas, a aquellas empresas que antepusieron la producci\u00f3n y el negocio a la seguridad de sus trabajadores y trabajadoras, a los bulos y a la desinformaci\u00f3n y a las batallas pol\u00edticas que tanto est\u00e1n dificultando y ralentizando la gesti\u00f3n postcat\u00e1strofe.<\/p>\n\n\n\n<p><strong>La magnitud de esta cat\u00e1strofe debe implicar desde ya un punto de inflexi\u00f3n, un antes y un despu\u00e9s, que nos obligue a cambiar comportamientos, normativas, protocolos y leyes, a revisar nuestras prioridades de salud ambiental, sociales y econ\u00f3micas (que deber\u00e1n ser por este orden, nunca al rev\u00e9s) y a modificar, en definitiva, nuestra forma de entender y gestionar el territorio y la prevenci\u00f3n de los riesgos. Creemos que, priorizar un modelo econ\u00f3mico que integre estos elementos y prioridades garantizar\u00e1 tambi\u00e9n que la econom\u00eda y empleos del futuro no dependan de asumir riesgos elevados e innecesarios.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/drive.google.com\/drive\/folders\/1ckC5aom2p1Io7U03VdB7G8wAXu3L_S3M?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">Nota de Prensa y Fotos<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>En relaci\u00f3n con la cat\u00e1strofe asociada a la DANA del 29 de octubre de 2024, el CIREF quiere destacar y manifestar las siguientes consideraciones: Ante todo, desde el Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial (CIREF), queremos manifestar nuestra m\u00e1xima solidaridad, afecto y cari\u00f1o para con todas las personas afectadas por la tragedia que se ha originado &#8230; <a title=\"Consideraciones sobre la DANA del 29 de octubre de 2024,\" class=\"read-more\" href=\"https:\/\/cirefluvial.com\/en\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/\" aria-label=\"Read more about Consideraciones sobre la DANA del 29 de octubre de 2024,\">Read more<\/a><\/p>","protected":false},"author":1,"featured_media":6459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[1,9],"tags":[],"class_list":["post-6451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-noticias","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"gutentor_comment":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consideraciones sobre la DANA del 29 de octubre de 2024, - CIREF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cirefluvial.com\/en\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consideraciones sobre la DANA del 29 de octubre de 2024, - CIREF\" \/>\n<meta property=\"og:description\" content=\"En relaci\u00f3n con la cat\u00e1strofe asociada a la DANA del 29 de octubre de 2024, el CIREF quiere destacar y manifestar las siguientes consideraciones: Ante todo, desde el Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial (CIREF), queremos manifestar nuestra m\u00e1xima solidaridad, afecto y cari\u00f1o para con todas las personas afectadas por la tragedia que se ha originado ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cirefluvial.com\/en\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"CIREF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-13T11:06:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-14T16:05:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"752\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fixer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Cirefluvial\" \/>\n<meta name=\"twitter:site\" content=\"@Cirefluvial\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"fixer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/\"},\"author\":{\"name\":\"fixer\",\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/person\/8e24d361e4490b3110a8a67807daa411\"},\"headline\":\"Consideraciones sobre la DANA del 29 de octubre de 2024,\",\"datePublished\":\"2024-11-13T11:06:43+00:00\",\"dateModified\":\"2024-11-14T16:05:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/\"},\"wordCount\":2107,\"publisher\":{\"@id\":\"https:\/\/cirefluvial.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg\",\"articleSection\":[\"Blog\",\"Noticias\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/\",\"url\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/\",\"name\":\"Consideraciones sobre la DANA del 29 de octubre de 2024, - CIREF\",\"isPartOf\":{\"@id\":\"https:\/\/cirefluvial.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg\",\"datePublished\":\"2024-11-13T11:06:43+00:00\",\"dateModified\":\"2024-11-14T16:05:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#primaryimage\",\"url\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg\",\"contentUrl\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg\",\"width\":1000,\"height\":752},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/cirefluvial.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consideraciones sobre la DANA del 29 de octubre de 2024,\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cirefluvial.com\/#website\",\"url\":\"https:\/\/cirefluvial.com\/\",\"name\":\"CIREF\",\"description\":\"Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial\",\"publisher\":{\"@id\":\"https:\/\/cirefluvial.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cirefluvial.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cirefluvial.com\/#organization\",\"name\":\"Centro Iberico de Restauraci\u00f3n Fluvial\",\"url\":\"https:\/\/cirefluvial.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png\",\"contentUrl\":\"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png\",\"width\":212,\"height\":80,\"caption\":\"Centro Iberico de Restauraci\u00f3n Fluvial\"},\"image\":{\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/\",\"https:\/\/x.com\/Cirefluvial\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/person\/8e24d361e4490b3110a8a67807daa411\",\"name\":\"fixer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cirefluvial.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g\",\"caption\":\"fixer\"},\"sameAs\":[\"https:\/\/cirefluvial.com\"],\"url\":\"https:\/\/cirefluvial.com\/en\/author\/fixer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consideraciones sobre la DANA del 29 de octubre de 2024, - CIREF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cirefluvial.com\/en\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/","og_locale":"en_GB","og_type":"article","og_title":"Consideraciones sobre la DANA del 29 de octubre de 2024, - CIREF","og_description":"En relaci\u00f3n con la cat\u00e1strofe asociada a la DANA del 29 de octubre de 2024, el CIREF quiere destacar y manifestar las siguientes consideraciones: Ante todo, desde el Centro Ib\u00e9rico de Restauraci\u00f3n Fluvial (CIREF), queremos manifestar nuestra m\u00e1xima solidaridad, afecto y cari\u00f1o para con todas las personas afectadas por la tragedia que se ha originado ... Read more","og_url":"https:\/\/cirefluvial.com\/en\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/","og_site_name":"CIREF","article_publisher":"https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/","article_published_time":"2024-11-13T11:06:43+00:00","article_modified_time":"2024-11-14T16:05:57+00:00","og_image":[{"width":1000,"height":752,"url":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg","type":"image\/jpeg"}],"author":"fixer","twitter_card":"summary_large_image","twitter_creator":"@Cirefluvial","twitter_site":"@Cirefluvial","twitter_misc":{"Written by":"fixer","Estimated reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#article","isPartOf":{"@id":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/"},"author":{"name":"fixer","@id":"https:\/\/cirefluvial.com\/#\/schema\/person\/8e24d361e4490b3110a8a67807daa411"},"headline":"Consideraciones sobre la DANA del 29 de octubre de 2024,","datePublished":"2024-11-13T11:06:43+00:00","dateModified":"2024-11-14T16:05:57+00:00","mainEntityOfPage":{"@id":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/"},"wordCount":2107,"publisher":{"@id":"https:\/\/cirefluvial.com\/#organization"},"image":{"@id":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg","articleSection":["Blog","Noticias"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/","url":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/","name":"Consideraciones sobre la DANA del 29 de octubre de 2024, - CIREF","isPartOf":{"@id":"https:\/\/cirefluvial.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#primaryimage"},"image":{"@id":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg","datePublished":"2024-11-13T11:06:43+00:00","dateModified":"2024-11-14T16:05:57+00:00","breadcrumb":{"@id":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#primaryimage","url":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg","contentUrl":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2024\/11\/Barranco-del-poyo-pichi.jpg","width":1000,"height":752},{"@type":"BreadcrumbList","@id":"https:\/\/cirefluvial.com\/consideraciones-sobre-la-dana-del-29-deoctubre-de-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cirefluvial.com\/"},{"@type":"ListItem","position":2,"name":"Consideraciones sobre la DANA del 29 de octubre de 2024,"}]},{"@type":"WebSite","@id":"https:\/\/cirefluvial.com\/#website","url":"https:\/\/cirefluvial.com\/","name":"CIREF","description":"Iberian Centre for River Restoration","publisher":{"@id":"https:\/\/cirefluvial.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cirefluvial.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cirefluvial.com\/#organization","name":"Centro Iberico de Restauraci\u00f3n Fluvial","url":"https:\/\/cirefluvial.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/","url":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png","contentUrl":"https:\/\/cirefluvial.com\/wp-content\/uploads\/2022\/05\/cabecera_logo_texto.png","width":212,"height":80,"caption":"Centro Iberico de Restauraci\u00f3n Fluvial"},"image":{"@id":"https:\/\/cirefluvial.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Centro-Ibrico-de-Restauracin-Fluvial-CIREF-1796315603933684\/","https:\/\/x.com\/Cirefluvial"]},{"@type":"Person","@id":"https:\/\/cirefluvial.com\/#\/schema\/person\/8e24d361e4490b3110a8a67807daa411","name":"fixer","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cirefluvial.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g","caption":"fixer"},"sameAs":["https:\/\/cirefluvial.com"],"url":"https:\/\/cirefluvial.com\/en\/author\/fixer\/"}]}},"_links":{"self":[{"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/posts\/6451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/comments?post=6451"}],"version-history":[{"count":20,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/posts\/6451\/revisions"}],"predecessor-version":[{"id":6482,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/posts\/6451\/revisions\/6482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/media\/6459"}],"wp:attachment":[{"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/media?parent=6451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/categories?post=6451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cirefluvial.com\/en\/wp-json\/wp\/v2\/tags?post=6451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}