{"id":2167,"date":"2023-07-13T19:50:48","date_gmt":"2023-07-13T17:50:48","guid":{"rendered":"https:\/\/cirefluvial.com\/congreso2023\/?page_id=2167"},"modified":"2026-05-06T19:18:09","modified_gmt":"2026-05-06T17:18:09","slug":"conclusiones-del-congreso","status":"publish","type":"page","link":"https:\/\/cirefluvial.com\/congreso2023\/en\/conclusiones-del-congreso\/","title":{"rendered":"Conclusiones del Congreso"},"content":{"rendered":"<div class=\"gb-container gb-container-f230f6b8\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-f5184bc6\">\n<div class=\"gb-grid-column gb-grid-column-6e28956b\"><div class=\"gb-container gb-container-6e28956b\"><div class=\"gb-inside-container\">\n\n<h5 class=\"gb-headline gb-headline-21916968 gb-headline-text\"><strong>IV IBERIAN CONFERENCE ON RIVER RESTORATION<br>RESTAURARIOS 2023 <\/strong><\/h5>\n\n\n\n<p class=\"eplus-wrapper\">El Congreso RestauraR\u00edos ha celebrado su cuarta edici\u00f3n en la ciudad de Toledo los d\u00edas 21, 22 y 23 de junio de 2023, con el objetivo de profundizar en el papel que la restauraci\u00f3n fluvial va a desempe\u00f1ar en un contexto de crisis clim\u00e1tica y cambio global.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">Han participado m\u00e1s de 420 personas y se ha mostrado un variado elenco de proyectos de restauraci\u00f3n, t\u00e9cnicas, experiencias y reflexiones a trav\u00e9s de 150 comunicaciones y 10 talleres pr\u00e1cticos, agrupados en 5 bloques tem\u00e1ticos. El congreso finaliz\u00f3 con una salida de campo el d\u00eda 23 en la que se visit\u00f3 el proyecto de restauraci\u00f3n del r\u00edo Manzanares a su paso por El Pardo.<\/p>\n\n\n\n<p class=\"eplus-wrapper\">A continuaci\u00f3n, se pueden ver las conclusiones del congreso divididas por grupos tem\u00e1ticos.&nbsp;<\/p>\n\n\n\n<a class=\"gb-button gb-button-fbfa6802 gb-button-text\" href=\"https:\/\/drive.google.com\/file\/d\/1Tq2miUTyzW870I-lbQj7Yks0BFIir-JY\/view?usp=sharing\" target=\"_blank\" rel=\"noopener noreferrer\">LIBRO DE ACTAS<\/a>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-a914169b\"><div class=\"gb-container gb-container-a914169b\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-61a636fb\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" class=\"gb-image gb-image-61a636fb\" src=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A1545-pichi.jpg\" alt=\"Foto del congreso 7\" title=\"_O9A1545-pichi\" srcset=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A1545-pichi.jpg 1000w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A1545-pichi-300x200.jpg 300w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A1545-pichi-768x511.jpg 768w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A1545-pichi-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-b71921aa\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-3a400167\"><span class=\"gb-icon\"><svg width=\"100%\" height=\"100%\" viewbox=\"0 0 47 47\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:1.41421;\"><g><g><g opacity=\"0.95\"><path d=\"M278.402,-0.67l-278.4,0.594l0.397,185.7l278.4,-0.594l-0.397,-185.7Z\" style=\"fill:#fff;\"><\/path><path d=\"M93,23.026l0,0.1l-46.4,0.1l23.2,-23.3l23.2,23.1Z\" style=\"fill:#1be8e1;fill-rule:nonzero;\"><\/path><path d=\"M92.976,-0.022l-46.3,0.098l0.049,23l46.3,-0.098l-0.049,-23Z\" style=\"fill:#0fef6d;\"><\/path><path d=\"M46.6,34.926l0,11.5l-11.6,0c0.1,-6.4 5.2,-11.5 11.6,-11.5Z\" style=\"fill:#0fef6d;fill-rule:nonzero;\"><\/path><path d=\"M93.1,23.126l-23.2,23.3l-23.3,-23.2l46.4,-0.1l0,-0.1l0.1,0.1Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M46.8,69.626c0,12.8 -10.4,23.3 -23.2,23.3l-0.1,-46.5c12.8,0 23.3,10.4 23.3,23.2Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M93.051,46.278l-46.4,0.099l0.099,46.5l46.4,-0.099l-0.099,-46.5Z\" style=\"fill:#0da1d1;\"><\/path><path d=\"M0.173,46.499l46.5,-0.099l-0.099,-46.4l-46.5,0.099l0.099,46.4Z\" style=\"fill:#0da1d1;\"><\/path><path d=\"M28.944,7.595c2.251,-3.341 6.791,-4.226 10.133,-1.974c3.341,2.251 4.226,6.791 1.974,10.133c-2.251,3.341 -6.792,4.226 -10.133,1.974c-3.341,-2.251 -4.226,-6.792 -1.974,-10.133Z\" style=\"fill:#0f80ef;\"><\/path><path d=\"M23.45,46.402l-23.4,0.05l0.1,46.5l23.4,-0.05l-0.1,-46.5Z\" style=\"fill:#0f80ef;\"><\/path><path d=\"M0,0.126c12.9,0 23.4,10.4 23.5,23.4l0,23l-23.4,0l-0.1,-46.4Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M46.6,23.326l0,23.1l-23.2,0c0.1,-12.8 10.4,-23.1 23.2,-23.1Z\" style=\"fill:#1be8e1;fill-rule:nonzero;\"><\/path><path d=\"M93,69.426l-46.3,0.1l23.1,-23.2l23.2,23.1Z\" style=\"fill:#fff;fill-rule:nonzero;\"><\/path><\/g><\/g><\/g><\/svg><\/span><span class=\"gb-headline-text\"><strong>Tema 1 . Recuperaci\u00f3n de la vida en los r\u00edos: fauna pisc\u00edcola (ictiofauna) y vegetaci\u00f3n de ribera<\/strong><\/span><\/h4>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-22ac525b\">\n<div class=\"gb-grid-column gb-grid-column-2809f198\"><div class=\"gb-container gb-container-2809f198\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-729e742c\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" class=\"gb-image gb-image-729e742c\" src=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A2675-pichi.jpg\" alt=\"Foto del congreso 5\" title=\"_O9A2675-pichi\" srcset=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A2675-pichi.jpg 1000w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A2675-pichi-300x200.jpg 300w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A2675-pichi-768x511.jpg 768w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A2675-pichi-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-2e32555f\"><div class=\"gb-container gb-container-2e32555f\"><div class=\"gb-inside-container\">\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-1b67c8\">\n<li class=\"eplus-wrapper\">La poblaci\u00f3n de especies ict\u00edcolas migradoras, en continua disminuci\u00f3n en la Pen\u00ednsula Ib\u00e9rica, puede mejorar gracias a las actuaciones de mejora de permeabilidad de obst\u00e1culos.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-cd361a\">\n<li class=\"eplus-wrapper\">Los planes de eliminaci\u00f3n y permeabilizaci\u00f3n de obst\u00e1culos son un instrumento que puede permitir avanzar de forma significativa en actuaciones de este tipo, tal y como muestran planes en marcha como el de Gip\u00fazcoa. El inventario y las metodolog\u00edas de priorizaci\u00f3n dentro de los mismos es imprescindible y debe ser siempre previo a la redacci\u00f3n de estos planes.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-332874\">\n<li class=\"eplus-wrapper\">Por otra parte, la priorizaci\u00f3n en las actuaciones de permeabilizaci\u00f3n, debe integrar el conocimiento sobre el grado de aislamiento gen\u00e9tico en las poblaciones de peces provocado por la compartimentaci\u00f3n del r\u00edo, dado que esto facilita la toma de decisiones.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/div>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-952cb4\">\n<li class=\"eplus-wrapper\">Se ha demostrado que las rampas <strong>naturalizadas<\/strong> para peces son funcionales. Estas pueden ser de muchos tipos, siendo las de flujo ascendente de un tipo especial. Se present\u00f3 una modelizaci\u00f3n hidr\u00e1ulica para la mejora del dise\u00f1o inicial de este tipo de rampas y la validaci\u00f3n biol\u00f3gica de su funcionalidad.\u00a0<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-ea432a\">\n<li class=\"eplus-wrapper\">Se ha <strong>mejorado en el conocimiento<\/strong> de la ictiofauna y en el funcionamiento de los pasos, pero los <strong>movimientos de descenso de la misma, <\/strong>junto con la evaluaci\u00f3n de los dispositivos<strong>, siguen siendo una asignatura pendiente<\/strong>\u00a0<\/li>\n<\/ul>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-7afd89a4\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-1e6f61de\"><span class=\"gb-icon\"><svg width=\"100%\" height=\"100%\" viewbox=\"0 0 47 47\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:1.41421;\"><g><g><g opacity=\"0.95\"><path d=\"M278.402,-0.67l-278.4,0.594l0.397,185.7l278.4,-0.594l-0.397,-185.7Z\" style=\"fill:#fff;\"><\/path><path d=\"M93,23.026l0,0.1l-46.4,0.1l23.2,-23.3l23.2,23.1Z\" style=\"fill:#1be8e1;fill-rule:nonzero;\"><\/path><path d=\"M92.976,-0.022l-46.3,0.098l0.049,23l46.3,-0.098l-0.049,-23Z\" style=\"fill:#0fef6d;\"><\/path><path d=\"M46.6,34.926l0,11.5l-11.6,0c0.1,-6.4 5.2,-11.5 11.6,-11.5Z\" style=\"fill:#0fef6d;fill-rule:nonzero;\"><\/path><path d=\"M93.1,23.126l-23.2,23.3l-23.3,-23.2l46.4,-0.1l0,-0.1l0.1,0.1Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M46.8,69.626c0,12.8 -10.4,23.3 -23.2,23.3l-0.1,-46.5c12.8,0 23.3,10.4 23.3,23.2Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M93.051,46.278l-46.4,0.099l0.099,46.5l46.4,-0.099l-0.099,-46.5Z\" style=\"fill:#0da1d1;\"><\/path><path d=\"M0.173,46.499l46.5,-0.099l-0.099,-46.4l-46.5,0.099l0.099,46.4Z\" style=\"fill:#0da1d1;\"><\/path><path d=\"M28.944,7.595c2.251,-3.341 6.791,-4.226 10.133,-1.974c3.341,2.251 4.226,6.791 1.974,10.133c-2.251,3.341 -6.792,4.226 -10.133,1.974c-3.341,-2.251 -4.226,-6.792 -1.974,-10.133Z\" style=\"fill:#0f80ef;\"><\/path><path d=\"M23.45,46.402l-23.4,0.05l0.1,46.5l23.4,-0.05l-0.1,-46.5Z\" style=\"fill:#0f80ef;\"><\/path><path d=\"M0,0.126c12.9,0 23.4,10.4 23.5,23.4l0,23l-23.4,0l-0.1,-46.4Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M46.6,23.326l0,23.1l-23.2,0c0.1,-12.8 10.4,-23.1 23.2,-23.1Z\" style=\"fill:#1be8e1;fill-rule:nonzero;\"><\/path><path d=\"M93,69.426l-46.3,0.1l23.1,-23.2l23.2,23.1Z\" style=\"fill:#fff;fill-rule:nonzero;\"><\/path><\/g><\/g><\/g><\/svg><\/span><span class=\"gb-headline-text\"><strong><strong>Tema 2. Caudal, sedimento, procesos y espacio<\/strong><\/strong><\/span><\/h4>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-866a927f\">\n<div class=\"gb-grid-column gb-grid-column-027d163e\"><div class=\"gb-container gb-container-027d163e\"><div class=\"gb-inside-container\">\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-4bb6e8\">\n<li class=\"eplus-wrapper\">Los proyectos de restauraci\u00f3n deben incluir una correcta caracterizaci\u00f3n ajustada a los objetivos de los mismos. Por ejemplo, antes de plantear actuaciones de derribo de presas es importante caracterizar los elementos hidromorfol\u00f3gicos principales y planificar la gesti\u00f3n del sedimento, como elemento clave.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-fe02d5\">\n<li class=\"eplus-wrapper\">Es fundamental el conocimiento del transporte de sedimento, para lo que se dispone de suficiente conocimiento cient\u00edfico-t\u00e9cnico con distintos enfoques tales como trabajos experimentales en campo o herramientas te\u00f3ricas para modelizar dicho transporte.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-86cd3b\">\n<li class=\"eplus-wrapper\">Resulta adecuado mejorar la conectividad lateral y vertical de los r\u00edos mediante la recuperaci\u00f3n de antiguos brazos, as\u00ed como valorar la reintroducci\u00f3n de la fracci\u00f3n gruesa del sedimento en los cauces principales. Ambas acciones pueden contribuir a revertir la incisi\u00f3n y aumentar la conectividad hidr\u00e1ulica lateral y la cota del nivel piezom\u00e9trico, mejorando adem\u00e1s la gesti\u00f3n de las inundaciones.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-4e5eb1b3\"><div class=\"gb-container gb-container-4e5eb1b3\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-0ff6ccb6\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" class=\"gb-image gb-image-0ff6ccb6\" src=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A2716-pichi.jpg\" alt=\"Foto del congreso 6\" title=\"_O9A2716-pichi\" srcset=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A2716-pichi.jpg 1000w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A2716-pichi-300x200.jpg 300w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A2716-pichi-768x511.jpg 768w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A2716-pichi-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n<\/div><\/div><\/div>\n<\/div>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-8882d4\">\n<li class=\"eplus-wrapper\">La aplicaci\u00f3n del protocolo de hidromorfolog\u00eda nos ha proporcionado un diagn\u00f3stico que sugiere que hay que mejorar la condici\u00f3n hidromorfol\u00f3gica y revisar la relaci\u00f3n entre esta condici\u00f3n y la determinaci\u00f3n del estado ecol\u00f3gico, as\u00ed como revisar los indicadores que analizan la conectividad vertical dentro del propio protocolo.<\/li>\n<\/ul>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-b5f3a7fa\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-27fd7adf\"><span class=\"gb-icon\"><svg width=\"100%\" height=\"100%\" viewbox=\"0 0 47 47\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:1.41421;\"><g><g><g opacity=\"0.95\"><path d=\"M278.402,-0.67l-278.4,0.594l0.397,185.7l278.4,-0.594l-0.397,-185.7Z\" style=\"fill:#fff;\"><\/path><path d=\"M93,23.026l0,0.1l-46.4,0.1l23.2,-23.3l23.2,23.1Z\" style=\"fill:#1be8e1;fill-rule:nonzero;\"><\/path><path d=\"M92.976,-0.022l-46.3,0.098l0.049,23l46.3,-0.098l-0.049,-23Z\" style=\"fill:#0fef6d;\"><\/path><path d=\"M46.6,34.926l0,11.5l-11.6,0c0.1,-6.4 5.2,-11.5 11.6,-11.5Z\" style=\"fill:#0fef6d;fill-rule:nonzero;\"><\/path><path d=\"M93.1,23.126l-23.2,23.3l-23.3,-23.2l46.4,-0.1l0,-0.1l0.1,0.1Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M46.8,69.626c0,12.8 -10.4,23.3 -23.2,23.3l-0.1,-46.5c12.8,0 23.3,10.4 23.3,23.2Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M93.051,46.278l-46.4,0.099l0.099,46.5l46.4,-0.099l-0.099,-46.5Z\" style=\"fill:#0da1d1;\"><\/path><path d=\"M0.173,46.499l46.5,-0.099l-0.099,-46.4l-46.5,0.099l0.099,46.4Z\" style=\"fill:#0da1d1;\"><\/path><path d=\"M28.944,7.595c2.251,-3.341 6.791,-4.226 10.133,-1.974c3.341,2.251 4.226,6.791 1.974,10.133c-2.251,3.341 -6.792,4.226 -10.133,1.974c-3.341,-2.251 -4.226,-6.792 -1.974,-10.133Z\" style=\"fill:#0f80ef;\"><\/path><path d=\"M23.45,46.402l-23.4,0.05l0.1,46.5l23.4,-0.05l-0.1,-46.5Z\" style=\"fill:#0f80ef;\"><\/path><path d=\"M0,0.126c12.9,0 23.4,10.4 23.5,23.4l0,23l-23.4,0l-0.1,-46.4Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M46.6,23.326l0,23.1l-23.2,0c0.1,-12.8 10.4,-23.1 23.2,-23.1Z\" style=\"fill:#1be8e1;fill-rule:nonzero;\"><\/path><path d=\"M93,69.426l-46.3,0.1l23.1,-23.2l23.2,23.1Z\" style=\"fill:#fff;fill-rule:nonzero;\"><\/path><\/g><\/g><\/g><\/svg><\/span><span class=\"gb-headline-text\"><strong><strong><strong>Tema 3. Gobernanza, gesti\u00f3n y protecci\u00f3n<\/strong><\/strong><\/strong><\/span><\/h4>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-65168da4\">\n<div class=\"gb-grid-column gb-grid-column-3beabaf9\"><div class=\"gb-container gb-container-3beabaf9\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-5cbffb10\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" class=\"gb-image gb-image-5cbffb10\" src=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0781-pichi.jpg\" alt=\"Foto del congreso 3\" title=\"_MG_0781-pichi\" srcset=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0781-pichi.jpg 1000w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0781-pichi-300x200.jpg 300w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0781-pichi-768x511.jpg 768w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0781-pichi-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-8f002735\"><div class=\"gb-container gb-container-8f002735\"><div class=\"gb-inside-container\">\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-40fc82\">\n<li class=\"eplus-wrapper\">La necesidad de di\u00e1logo y cooperaci\u00f3n entre los diversos actores locales en el territorio es un aspecto fundamental para el desarrollo de los proyectos de restauraci\u00f3n.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-e1a8df\">\n<li class=\"eplus-wrapper\"><strong>Resulta imprescindible generar sinergias entre las <\/strong>administraciones competentes, el mundo acad\u00e9mico, actores locales, movimientos conservacionistas y el sector privado.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-b20916\">\n<li class=\"eplus-wrapper\">Para asegurar el \u00e9xito de las labores de restauraci\u00f3n resultan claves una buena comunicaci\u00f3n y divulgaci\u00f3n.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-ca5351\">\n<li class=\"eplus-wrapper\">Se ha puesto de manifiesto, a su vez, la relevancia de imbricar las pol\u00edticas e instrumentos generales de conservaci\u00f3n y restauraci\u00f3n con la planificaci\u00f3n hidrol\u00f3gica.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-f3146f\">\n<li class=\"eplus-wrapper\">Una de las actuaciones <em>estrella<\/em> para la mejora del estado ecol\u00f3gico sigue siendo la eliminaci\u00f3n de barreras y este congreso ha mostrado experiencias promovidas no solo por la administraci\u00f3n, sino tambi\u00e9n por otras entidades de manera coordinada.\u00a0<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/div>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-108924\">\n<li class=\"eplus-wrapper\">Es fundamental fomentar y desarrollar el estudio sobre la estructura y funci\u00f3n de los ecosistemas fluviales para mejorar su gesti\u00f3n y protecci\u00f3n o plantear acciones de restauraci\u00f3n. \u00a0<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-524cff\">\n<li class=\"eplus-wrapper\">Se debe abordar la restauraci\u00f3n desde distintos enfoques, con t\u00e9cnicas diversas e involucrando a varios actores, tanto desde la planificaci\u00f3n como desde la gesti\u00f3n de los recursos.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-98222b\">\n<li class=\"eplus-wrapper\">Un avance en la restauraci\u00f3n fluvial es conseguir cambiar el paradigma de las \u201climpiezas\u201d, dragados de cauces o protecci\u00f3n de m\u00e1rgenes como \u00fanicas v\u00edas de mejora de los r\u00edos, encaminando estas actuaciones hacia la restauraci\u00f3n ecol\u00f3gica, integrada en la infraestructura verde territorial.\u00a0<\/li>\n<\/ul>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-8dbb39ea\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-853e2424\"><span class=\"gb-icon\"><svg width=\"100%\" height=\"100%\" viewbox=\"0 0 47 47\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:1.41421;\"><g><g><g opacity=\"0.95\"><path d=\"M278.402,-0.67l-278.4,0.594l0.397,185.7l278.4,-0.594l-0.397,-185.7Z\" style=\"fill:#fff;\"><\/path><path d=\"M93,23.026l0,0.1l-46.4,0.1l23.2,-23.3l23.2,23.1Z\" style=\"fill:#1be8e1;fill-rule:nonzero;\"><\/path><path d=\"M92.976,-0.022l-46.3,0.098l0.049,23l46.3,-0.098l-0.049,-23Z\" style=\"fill:#0fef6d;\"><\/path><path d=\"M46.6,34.926l0,11.5l-11.6,0c0.1,-6.4 5.2,-11.5 11.6,-11.5Z\" style=\"fill:#0fef6d;fill-rule:nonzero;\"><\/path><path d=\"M93.1,23.126l-23.2,23.3l-23.3,-23.2l46.4,-0.1l0,-0.1l0.1,0.1Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M46.8,69.626c0,12.8 -10.4,23.3 -23.2,23.3l-0.1,-46.5c12.8,0 23.3,10.4 23.3,23.2Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M93.051,46.278l-46.4,0.099l0.099,46.5l46.4,-0.099l-0.099,-46.5Z\" style=\"fill:#0da1d1;\"><\/path><path d=\"M0.173,46.499l46.5,-0.099l-0.099,-46.4l-46.5,0.099l0.099,46.4Z\" style=\"fill:#0da1d1;\"><\/path><path d=\"M28.944,7.595c2.251,-3.341 6.791,-4.226 10.133,-1.974c3.341,2.251 4.226,6.791 1.974,10.133c-2.251,3.341 -6.792,4.226 -10.133,1.974c-3.341,-2.251 -4.226,-6.792 -1.974,-10.133Z\" style=\"fill:#0f80ef;\"><\/path><path d=\"M23.45,46.402l-23.4,0.05l0.1,46.5l23.4,-0.05l-0.1,-46.5Z\" style=\"fill:#0f80ef;\"><\/path><path d=\"M0,0.126c12.9,0 23.4,10.4 23.5,23.4l0,23l-23.4,0l-0.1,-46.4Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M46.6,23.326l0,23.1l-23.2,0c0.1,-12.8 10.4,-23.1 23.2,-23.1Z\" style=\"fill:#1be8e1;fill-rule:nonzero;\"><\/path><path d=\"M93,69.426l-46.3,0.1l23.1,-23.2l23.2,23.1Z\" style=\"fill:#fff;fill-rule:nonzero;\"><\/path><\/g><\/g><\/g><\/svg><\/span><span class=\"gb-headline-text\"><strong><strong><strong><strong>Tema 4. R\u00edos y educaci\u00f3n ambiental, concienciaci\u00f3n, divulgaci\u00f3n y participaci\u00f3n.<\/strong><\/strong><\/strong><\/strong><\/span><\/h4>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-54df8294\">\n<div class=\"gb-grid-column gb-grid-column-003bc91c\"><div class=\"gb-container gb-container-003bc91c\"><div class=\"gb-inside-container\">\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-c1bd02\">\n<li class=\"eplus-wrapper\">La\u00a0<strong>educaci\u00f3n ambiental, la integraci\u00f3n y participaci\u00f3n de las poblaciones locales en los proyectos de restauraci\u00f3n es un aspecto reiterado y muchas veces reivindicado.<\/strong>\u00a0Conocer las variadas experiencias realizadas estos a\u00f1os, ha sido una oportunidad que se nos ha brindado en este congreso.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-b4b242\">\n<li class=\"eplus-wrapper\">Conocer las\u00a0<strong>percepciones de la ciudadan\u00eda,<\/strong>\u00a0experimentar con\u00a0<strong>actividades que concitan la creatividad<\/strong>, el\u00a0<strong>contacto emocional y f\u00edsico con los r\u00edos<\/strong>\u00a0y la\u00a0<strong>hibridaci\u00f3n de disciplinas <\/strong>culturales y art\u00edsticas proporcionan resultados muy deseables.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-6fc02c\">\n<li class=\"eplus-wrapper\">The\u00a0<strong>fortalecimiento de las capacidades sociales<\/strong> y la participaci\u00f3n en la toma de decisiones es m\u00e1s que nunca necesaria, adem\u00e1s de\u00a0<strong>disminuir la vulnerabilidad<\/strong>\u00a0frente a los riesgos de convivir con el r\u00edo.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-cb6d2d\">\n<li class=\"eplus-wrapper\">Trabajar con las gentes del territorio en la b\u00fasqueda del\u00a0<strong>paisaje cultural tradicional fluvial<\/strong>, y los usos hist\u00f3ricos las fideliza, y sirve de garant\u00eda de que haya una custodia posterior a las obras.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-40fd812f\"><div class=\"gb-container gb-container-40fd812f\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-9bb2e018\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" class=\"gb-image gb-image-9bb2e018\" src=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0146-pichi.jpg\" alt=\"Foto del congreso 2\" title=\"_MG_0146-pichi\" srcset=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0146-pichi.jpg 1000w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0146-pichi-300x200.jpg 300w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0146-pichi-768x511.jpg 768w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0146-pichi-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n<\/div><\/div><\/div>\n<\/div>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-bc11a1\">\n<li class=\"eplus-wrapper\">Se ha constatado la importancia de\u00a0<strong>recuperar la memoria de los r\u00edos absolutamente borrados,<\/strong>\u00a0sobre todo en los entornos urbanos donde es frecuente que no quede ninguna huella de los mismos. En entornos rurales, si se da el caso, es igualmente necesario.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-445373\">\n<li class=\"eplus-wrapper\"><strong>El conflicto<\/strong>\u00a0en torno a intervenciones de restauraci\u00f3n\u00a0debe de ser una<strong> oportunidad de transformaci\u00f3n y como tal no ha de eludirse<\/strong>.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-ffe0a8\">\n<li class=\"eplus-wrapper\">La\u00a0<strong>participaci\u00f3n ha de ser real<\/strong>, empezar en las fases previas a los proyectos, y siguiendo durante la realizaci\u00f3n de las obras y al final, a modo de retorno a la poblaci\u00f3n.<\/li>\n<\/ul>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-133b5012\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-83e43f16\"><span class=\"gb-icon\"><svg width=\"100%\" height=\"100%\" viewbox=\"0 0 47 47\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:1.41421;\"><g><g><g opacity=\"0.95\"><path d=\"M278.402,-0.67l-278.4,0.594l0.397,185.7l278.4,-0.594l-0.397,-185.7Z\" style=\"fill:#fff;\"><\/path><path d=\"M93,23.026l0,0.1l-46.4,0.1l23.2,-23.3l23.2,23.1Z\" style=\"fill:#1be8e1;fill-rule:nonzero;\"><\/path><path d=\"M92.976,-0.022l-46.3,0.098l0.049,23l46.3,-0.098l-0.049,-23Z\" style=\"fill:#0fef6d;\"><\/path><path d=\"M46.6,34.926l0,11.5l-11.6,0c0.1,-6.4 5.2,-11.5 11.6,-11.5Z\" style=\"fill:#0fef6d;fill-rule:nonzero;\"><\/path><path d=\"M93.1,23.126l-23.2,23.3l-23.3,-23.2l46.4,-0.1l0,-0.1l0.1,0.1Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M46.8,69.626c0,12.8 -10.4,23.3 -23.2,23.3l-0.1,-46.5c12.8,0 23.3,10.4 23.3,23.2Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M93.051,46.278l-46.4,0.099l0.099,46.5l46.4,-0.099l-0.099,-46.5Z\" style=\"fill:#0da1d1;\"><\/path><path d=\"M0.173,46.499l46.5,-0.099l-0.099,-46.4l-46.5,0.099l0.099,46.4Z\" style=\"fill:#0da1d1;\"><\/path><path d=\"M28.944,7.595c2.251,-3.341 6.791,-4.226 10.133,-1.974c3.341,2.251 4.226,6.791 1.974,10.133c-2.251,3.341 -6.792,4.226 -10.133,1.974c-3.341,-2.251 -4.226,-6.792 -1.974,-10.133Z\" style=\"fill:#0f80ef;\"><\/path><path d=\"M23.45,46.402l-23.4,0.05l0.1,46.5l23.4,-0.05l-0.1,-46.5Z\" style=\"fill:#0f80ef;\"><\/path><path d=\"M0,0.126c12.9,0 23.4,10.4 23.5,23.4l0,23l-23.4,0l-0.1,-46.4Z\" style=\"fill:#0dd190;fill-rule:nonzero;\"><\/path><path d=\"M46.6,23.326l0,23.1l-23.2,0c0.1,-12.8 10.4,-23.1 23.2,-23.1Z\" style=\"fill:#1be8e1;fill-rule:nonzero;\"><\/path><path d=\"M93,69.426l-46.3,0.1l23.1,-23.2l23.2,23.1Z\" style=\"fill:#fff;fill-rule:nonzero;\"><\/path><\/g><\/g><\/g><\/svg><\/span><span class=\"gb-headline-text\"><strong><strong><strong><strong><strong>Tema 5. R\u00edos urbanos: reto en la restauraci\u00f3n fluvial.<\/strong><\/strong><\/strong><\/strong><\/strong><\/span><\/h4>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-b0faf691\">\n<div class=\"gb-grid-column gb-grid-column-974f0491\"><div class=\"gb-container gb-container-974f0491\"><div class=\"gb-inside-container\">\n\n<figure class=\"gb-block-image gb-block-image-cdfe0d5b\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" class=\"gb-image gb-image-cdfe0d5b\" src=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0136-pichi.jpg\" alt=\"Foto del congreso 1\" title=\"_MG_0136-pichi\" srcset=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0136-pichi.jpg 1000w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0136-pichi-300x200.jpg 300w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0136-pichi-768x511.jpg 768w, https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/MG_0136-pichi-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-8318c70e\"><div class=\"gb-container gb-container-8318c70e\"><div class=\"gb-inside-container\">\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-d98a57\">\n<li class=\"eplus-wrapper\">Existe incertidumbre sobre la definici\u00f3n y delimitaci\u00f3n de los tramos urbanos de cauces p\u00fablicos.\u00a0<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-b03263\">\n<li class=\"eplus-wrapper\">Los tramos urbanos naturalizados en los que se han retirado infraestructuras duras y se ha mejorado la din\u00e1mica fluvial, aportan m\u00e1s beneficios ecosist\u00e9micos y sociales que los r\u00edos completamente encauzados.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-330b8c\">\n<li class=\"eplus-wrapper\">Tras las actuaciones es imprescindible una gesti\u00f3n y seguimiento que permita evaluar el grado de cumplimiento de los objetivos establecidos y que contribuya a la permeabilidad de las medidas.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list eplus-wrapper eplus-styles-uid-c2cf07\">\n<li class=\"eplus-wrapper\">En tramos urbanos no son \u00fatiles los indicadores hidromorfol\u00f3gicos habituales. Ser\u00eda conveniente desarrollar indicadores espec\u00edficos.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-66df2f2b\"><div class=\"gb-inside-container\">\n\n<h2 class=\"gb-headline gb-headline-83932c17\"><span class=\"gb-icon\"><svg style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:1.41421;\" xml:space=\"preserve\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewbox=\"0 0 47 47\" height=\"100%\" width=\"100%\"><g><g><g opacity=\"0.95\"><path style=\"fill:#fff;\" d=\"M231.802,-0.647l-278.4,0.594l0.397,185.7l278.4,-0.594l-0.397,-185.7Z\"><\/path><path style=\"fill:#1be8e1;fill-rule:nonzero;\" d=\"M46.4,23.049l0,0.1l-46.4,0.1l23.2,-23.3l23.2,23.1Z\"><\/path><path style=\"fill:#0fef6d;\" d=\"M46.376,0l-46.3,0.099l0.049,23l46.3,-0.099l-0.049,-23Z\"><\/path><path style=\"fill:#0fef6d;fill-rule:nonzero;\" d=\"M0,34.949l0,11.5l-11.6,0c0.1,-6.4 5.2,-11.5 11.6,-11.5Z\"><\/path><path style=\"fill:#0dd190;fill-rule:nonzero;\" d=\"M46.5,23.149l-23.2,23.3l-23.3,-23.2l46.4,-0.1l0,-0.1l0.1,0.1Z\"><\/path><path style=\"fill:#0dd190;fill-rule:nonzero;\" d=\"M0.2,69.649c0,12.8 -10.4,23.3 -23.2,23.3l-0.1,-46.5c12.8,0 23.3,10.4 23.3,23.2Z\"><\/path><path style=\"fill:#0da1d1;\" d=\"M46.451,46.3l-46.4,0.099l0.099,46.5l46.4,-0.099l-0.099,-46.5Z\"><\/path><path style=\"fill:#0da1d1;\" d=\"M51.928,7.54c2.239,-3.35 6.776,-4.252 10.126,-2.013c3.349,2.239 4.251,6.776 2.012,10.126c-2.239,3.35 -6.776,4.252 -10.126,2.013c-3.349,-2.239 -4.251,-6.776 -2.012,-10.126Z\"><\/path><path style=\"fill:#0da1d1;\" d=\"M-46.427,46.522l46.5,-0.1l-0.099,-46.4l-46.5,0.1l0.099,46.4Z\"><\/path><path style=\"fill:#0da1d1;\" d=\"M23.136,13.006l-10.161,10.204l10.204,10.161l10.161,-10.204l-10.204,-10.161Z\"><\/path><path style=\"fill:#0f80ef;\" d=\"M69.826,-0.176l-23.5,0.05l0.148,69.5l23.5,-0.05l-0.148,-69.5Z\"><\/path><path style=\"fill:#1be8e1;fill-rule:nonzero;\" d=\"M0,23.349l0,23.1l-23.2,0c0.1,-12.8 10.4,-23.1 23.2,-23.1Z\"><\/path><path style=\"fill:#fff;fill-rule:nonzero;\" d=\"M46.4,69.449l-46.3,0.1l23.1,-23.2l23.2,23.1Z\"><\/path><\/g><\/g><\/g><\/svg><\/span><span class=\"gb-headline-text\">Organisation<\/span><\/h2>\n\n\n\n<p class=\"gb-headline gb-headline-e0f1cbda gb-headline-text\">The team of the Conference, RestauraRios 2023 is formed by different Committees:  Organiser, Scientific and Honour formed by interdisciplinary experts of river restoration coming from public and private sectors and NGO\u2019s.<\/p>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-cadfd000\">\n\n<a class=\"gb-button gb-button-d2849cab gb-button-text\" href=\"https:\/\/cirefluvial.com\/congreso2023\/en\/conoce-al-equipo\/\">COMMITTEES<\/a>\n\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Tema 1 . Recuperaci\u00f3n de la vida en los r\u00edos: fauna pisc\u00edcola (ictiofauna) y vegetaci\u00f3n de ribera Tema 2. Caudal, &#8230; <a title=\"Conclusiones del Congreso\" class=\"read-more\" href=\"https:\/\/cirefluvial.com\/congreso2023\/en\/conclusiones-del-congreso\/\" aria-label=\"Read more about Conclusiones del Congreso\">Read more<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"editor_plus_copied_stylings":"{}","footnotes":""},"class_list":["post-2167","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conclusiones del Congreso - IV Congreso RestauraRios 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cirefluvial.com\/congreso2023\/en\/conclusiones-del-congreso\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conclusiones del Congreso - IV Congreso RestauraRios 2023\" \/>\n<meta property=\"og:description\" content=\"Tema 1 . Recuperaci\u00f3n de la vida en los r\u00edos: fauna pisc\u00edcola (ictiofauna) y vegetaci\u00f3n de ribera Tema 2. Caudal, ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cirefluvial.com\/congreso2023\/en\/conclusiones-del-congreso\/\" \/>\n<meta property=\"og:site_name\" content=\"IV Congreso RestauraRios 2023\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100064709197688\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T17:18:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A1545-pichi.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Cirefluvial\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/conclusiones-del-congreso\\\/\",\"url\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/conclusiones-del-congreso\\\/\",\"name\":\"Conclusiones del Congreso - IV Congreso RestauraRios 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/conclusiones-del-congreso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/conclusiones-del-congreso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/O9A1545-pichi.jpg\",\"datePublished\":\"2023-07-13T17:50:48+00:00\",\"dateModified\":\"2026-05-06T17:18:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/conclusiones-del-congreso\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/conclusiones-del-congreso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/conclusiones-del-congreso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/O9A1545-pichi.jpg\",\"contentUrl\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/O9A1545-pichi.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/conclusiones-del-congreso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conclusiones del Congreso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/#website\",\"url\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/\",\"name\":\"IV Congreso RestauraRios 2023\",\"description\":\"IV Congreso RestauraRios 2023\",\"publisher\":{\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/#organization\",\"name\":\"IV Congreso RestauraRios 2023\",\"url\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo-Corrrgido.png\",\"contentUrl\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo-Corrrgido.png\",\"width\":420,\"height\":170,\"caption\":\"IV Congreso RestauraRios 2023\"},\"image\":{\"@id\":\"https:\\\/\\\/cirefluvial.com\\\/congreso2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100064709197688\",\"https:\\\/\\\/x.com\\\/Cirefluvial\",\"https:\\\/\\\/www.instagram.com\\\/ciref_fluvial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conclusiones del Congreso - IV Congreso RestauraRios 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cirefluvial.com\/congreso2023\/en\/conclusiones-del-congreso\/","og_locale":"en_GB","og_type":"article","og_title":"Conclusiones del Congreso - IV Congreso RestauraRios 2023","og_description":"Tema 1 . Recuperaci\u00f3n de la vida en los r\u00edos: fauna pisc\u00edcola (ictiofauna) y vegetaci\u00f3n de ribera Tema 2. Caudal, ... Read more","og_url":"https:\/\/cirefluvial.com\/congreso2023\/en\/conclusiones-del-congreso\/","og_site_name":"IV Congreso RestauraRios 2023","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100064709197688","article_modified_time":"2026-05-06T17:18:09+00:00","og_image":[{"url":"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A1545-pichi.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Cirefluvial","twitter_misc":{"Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cirefluvial.com\/congreso2023\/conclusiones-del-congreso\/","url":"https:\/\/cirefluvial.com\/congreso2023\/conclusiones-del-congreso\/","name":"Conclusiones del Congreso - IV Congreso RestauraRios 2023","isPartOf":{"@id":"https:\/\/cirefluvial.com\/congreso2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cirefluvial.com\/congreso2023\/conclusiones-del-congreso\/#primaryimage"},"image":{"@id":"https:\/\/cirefluvial.com\/congreso2023\/conclusiones-del-congreso\/#primaryimage"},"thumbnailUrl":"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A1545-pichi.jpg","datePublished":"2023-07-13T17:50:48+00:00","dateModified":"2026-05-06T17:18:09+00:00","breadcrumb":{"@id":"https:\/\/cirefluvial.com\/congreso2023\/conclusiones-del-congreso\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cirefluvial.com\/congreso2023\/conclusiones-del-congreso\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cirefluvial.com\/congreso2023\/conclusiones-del-congreso\/#primaryimage","url":"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A1545-pichi.jpg","contentUrl":"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2023\/07\/O9A1545-pichi.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cirefluvial.com\/congreso2023\/conclusiones-del-congreso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cirefluvial.com\/congreso2023\/"},{"@type":"ListItem","position":2,"name":"Conclusiones del Congreso"}]},{"@type":"WebSite","@id":"https:\/\/cirefluvial.com\/congreso2023\/#website","url":"https:\/\/cirefluvial.com\/congreso2023\/","name":"IV Congreso RestauraRios 2023","description":"IV Congreso RestauraRios 2023","publisher":{"@id":"https:\/\/cirefluvial.com\/congreso2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cirefluvial.com\/congreso2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cirefluvial.com\/congreso2023\/#organization","name":"IV Congreso RestauraRios 2023","url":"https:\/\/cirefluvial.com\/congreso2023\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cirefluvial.com\/congreso2023\/#\/schema\/logo\/image\/","url":"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2022\/01\/Logo-Corrrgido.png","contentUrl":"https:\/\/cirefluvial.com\/congreso2023\/wp-content\/uploads\/2022\/01\/Logo-Corrrgido.png","width":420,"height":170,"caption":"IV Congreso RestauraRios 2023"},"image":{"@id":"https:\/\/cirefluvial.com\/congreso2023\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100064709197688","https:\/\/x.com\/Cirefluvial","https:\/\/www.instagram.com\/ciref_fluvial\/"]}]}},"_links":{"self":[{"href":"https:\/\/cirefluvial.com\/congreso2023\/en\/wp-json\/wp\/v2\/pages\/2167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cirefluvial.com\/congreso2023\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cirefluvial.com\/congreso2023\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cirefluvial.com\/congreso2023\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cirefluvial.com\/congreso2023\/en\/wp-json\/wp\/v2\/comments?post=2167"}],"version-history":[{"count":4,"href":"https:\/\/cirefluvial.com\/congreso2023\/en\/wp-json\/wp\/v2\/pages\/2167\/revisions"}],"predecessor-version":[{"id":2210,"href":"https:\/\/cirefluvial.com\/congreso2023\/en\/wp-json\/wp\/v2\/pages\/2167\/revisions\/2210"}],"wp:attachment":[{"href":"https:\/\/cirefluvial.com\/congreso2023\/en\/wp-json\/wp\/v2\/media?parent=2167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}